{"id":1163,"date":"2023-11-16T14:04:51","date_gmt":"2023-11-16T14:04:51","guid":{"rendered":"https:\/\/www.hop-on-hop-off.net\/?page_id=1163"},"modified":"2026-04-28T09:16:02","modified_gmt":"2026-04-28T09:16:02","slug":"los-angeles","status":"publish","type":"page","link":"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/","title":{"rendered":"Los Angeles: Hop-on\/Hop-off"},"content":{"rendered":"<style>.kb-image1163_6bed87-ea .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1163_6bed87-ea size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"501\" src=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-star-line.jpg\" alt=\"Hop-on\/ Hop-off Los Angeles: Star Line Tours\" class=\"kb-img wp-image-1171\" srcset=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-star-line.jpg 800w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-star-line-300x188.jpg 300w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-star-line-768x481.jpg 768w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-star-line-18x12.jpg 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>\u00a9 FrimuFilms\/ Shutterstock<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Hier finden Sie Informationen zu Stadtrundfahrten mit dem Hop-on\/Hop-off-Bus in Los Angeles. Wir informieren Sie \u00fcber Haltestellen, Fahrpl\u00e4ne und Preise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Tickets k\u00f6nnen Sie direkt bei unseren Partnern buchen und auf Ihr Handy laden. F\u00fcr den Verkauf erhalten wir eine kleine Provision. Der Preis bleibt f\u00fcr Sie selbstverst\u00e4ndlich gleich.<\/p>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1163_b0bf09-f8{margin-bottom:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);}.kb-row-layout-id1163_b0bf09-f8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1163_b0bf09-f8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1163_b0bf09-f8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1163_b0bf09-f8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1163_b0bf09-f8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1163_b0bf09-f8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1163_b0bf09-f8 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1163_1ec5d2-26 > .kt-inside-inner-col,.kadence-column1163_1ec5d2-26 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_1ec5d2-26 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_1ec5d2-26 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_1ec5d2-26 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_1ec5d2-26 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_1ec5d2-26{position:relative;}@media all and (max-width: 1024px){.kadence-column1163_1ec5d2-26 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_1ec5d2-26 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_1ec5d2-26\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1163_209d19-96, .wp-block-kadence-advancedheading.kt-adv-heading1163_209d19-96[data-kb-block=\"kb-adv-heading1163_209d19-96\"]{text-align:center;font-style:normal;background-color:#b51310;border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}.wp-block-kadence-advancedheading.kt-adv-heading1163_209d19-96 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1163_209d19-96[data-kb-block=\"kb-adv-heading1163_209d19-96\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1163_209d19-96 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1163_209d19-96[data-kb-block=\"kb-adv-heading1163_209d19-96\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1163_209d19-96, .wp-block-kadence-advancedheading.kt-adv-heading1163_209d19-96[data-kb-block=\"kb-adv-heading1163_209d19-96\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1163_209d19-96, .wp-block-kadence-advancedheading.kt-adv-heading1163_209d19-96[data-kb-block=\"kb-adv-heading1163_209d19-96\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}<\/style>\n<h2 id=\"0-valencia-bus-tur%C3%ADstic\" class=\"kt-adv-heading1163_209d19-96 wp-block-kadence-advancedheading has-base-3-color has-text-color\" data-kb-block=\"kb-adv-heading1163_209d19-96\">Big Bus Los Angeles<\/h2>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1163_5903cf-26{margin-bottom:0px;}.kb-row-layout-id1163_5903cf-26 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1163_5903cf-26 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1163_5903cf-26 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1163_5903cf-26 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1163_5903cf-26 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1163_5903cf-26 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1163_5903cf-26 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1163_b48652-04 > .kt-inside-inner-col,.kadence-column1163_b48652-04 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_b48652-04 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_b48652-04 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_b48652-04 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_b48652-04 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_b48652-04{position:relative;}@media all and (max-width: 1024px){.kadence-column1163_b48652-04 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_b48652-04 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_b48652-04\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1163_c7d402-a6 > .kt-inside-inner-col,.kadence-column1163_c7d402-a6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_c7d402-a6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_c7d402-a6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_c7d402-a6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_c7d402-a6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_c7d402-a6{position:relative;}.kadence-column1163_c7d402-a6, .kt-inside-inner-col > .kadence-column1163_c7d402-a6:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column1163_c7d402-a6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_c7d402-a6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_c7d402-a6\"><div class=\"kt-inside-inner-col\">\n<div data-tiqets-widget=\"availability\" data-layout=\"full\" data-orientation=\"horizontal\" data-product-id=\"1009752\" data-partner=\"hopon\"><\/div>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1163_d8001d-ab, .wp-block-kadence-advancedheading.kt-adv-heading1163_d8001d-ab[data-kb-block=\"kb-adv-heading1163_d8001d-ab\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1163_d8001d-ab mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1163_d8001d-ab[data-kb-block=\"kb-adv-heading1163_d8001d-ab\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1163_d8001d-ab img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1163_d8001d-ab[data-kb-block=\"kb-adv-heading1163_d8001d-ab\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p id=\"1-valencia-bus-turistic-bietet-seit-1999-stadtrundfahrten-an-die-roten-hop-onhop-off-busse-bedienen-haltestellen-die-%C3%BCber-ganz-valencia-verteilt-sind-an-bord-gibt-es-einen-audioguide-in-10-sprachen\" class=\"kt-adv-heading1163_d8001d-ab wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1163_d8001d-ab\">Big Bus ist einer der gr\u00f6\u00dften Anbieter f\u00fcr Hop-on\/Hop-off-Touren und weltweit in zahlreichen St\u00e4dten vertreten.<\/p>\n\n\n<style>.kadence-column1163_f529d5-70 > .kt-inside-inner-col,.kadence-column1163_f529d5-70 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_f529d5-70 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_f529d5-70 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_f529d5-70 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_f529d5-70 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_f529d5-70{position:relative;}.kadence-column1163_f529d5-70, .kt-inside-inner-col > .kadence-column1163_f529d5-70:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column1163_f529d5-70 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_f529d5-70 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_f529d5-70\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id1163_27e89d-c7 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:5px;}.kt-accordion-id1163_27e89d-c7 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id1163_27e89d-c7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:var(--contrast);padding-top:10px;padding-right:14px;padding-bottom:10px;padding-left:14px;}.kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--contrast);}.kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--contrast);}.kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id1163_27e89d-c7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1163_27e89d-c7 .kt-blocks-accordion-header:focus-visible{color:#444444;background:var(--base-2);border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--base-2);}.kt-accordion-id1163_27e89d-c7 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1163_27e89d-c7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#e51b22;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1163_27e89d-c7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#e51b22;}@media all and (max-width: 1024px){.kt-accordion-id1163_27e89d-c7 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id1163_27e89d-c7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id1163_27e89d-c7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1163_27e89d-c7 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id1163_27e89d-c7 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1163_27e89d-c7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id1163_27e89d-c7 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id1163_27e89d-c7 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:5px;}.kt-accordion-id1163_27e89d-c7 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id1163_27e89d-c7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id1163_27e89d-c7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1163_27e89d-c7 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id1163_27e89d-c7 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1163_27e89d-c7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id1163_27e89d-c7 kt-accordion-has-7-panes kt-active-pane-3 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane1163_d4d800-d3\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Routen &amp; Haltestellen<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e91c56-87:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e91c56-87 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e91c56-87 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e91c56-87 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e91c56-87 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1163_e91c56-87 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1163_e91c56-87 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1163_701ca4-e7 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_701ca4-e7\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">2 Routen \u2013&nbsp;20+ Haltestellen<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_acc5d5-c2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_acc5d5-c2\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Optional: Celebrity Homes + TCL Chinese Theatre Walking Tour<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_0b4568-6f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_0b4568-6f\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/www.bigbustours.com\/en\/los-angeles\/los-angeles-routes-and-tour-maps?utm_source=Commission_Junction&amp;utm_medium=Affiliate_Marketing&amp;utm_campaign=Patrick+K%C3%BChne_101037000&amp;cjevent=9b4da8bd094a11f0806402a30a18b8f8\" target=\"_blank\" rel=\"noopener\" title=\"\">Karte mit Route &amp; Haltestellen<\/a><\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane1163_396b0e-71\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Fahrplan Rote Linie\/ Hollywood<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4f5da6-83:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4f5da6-83 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4f5da6-83 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4f5da6-83 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4f5da6-83 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1163_4f5da6-83 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1163_4f5da6-83 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1163_b8ea2f-7f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_b8ea2f-7f\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Erste Abfahrt: 10:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_8f59dc-bb .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_8f59dc-bb\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Letzte Abfahrt: 16:30<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_d8ef59-25 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_d8ef59-25\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Frequenz: alle 45-60 Minuten<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_d4056a-ee .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_d4056a-ee\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Dauer der Rundfahrt: 2 Stunden<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_704f76-00 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_704f76-00\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Starthaltestelle: Big Bus Visitor Center Hollywood<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane1163_f4dccf-1f\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Fahrplan Blaue Linie\/ Beach Loop<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_576f30-73:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_576f30-73 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_576f30-73 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_576f30-73 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_576f30-73 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1163_576f30-73 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1163_576f30-73 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1163_8a382f-25 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_8a382f-25\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">T\u00e4gliche Abfahrten: 10:45\/ 11:45\/ 13:00\/ 14:00 und 15:15<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_b36f8b-7a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_b36f8b-7a\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Dauer der Rundfahrt: 30 Minuten<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_efdf36-b4 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_efdf36-b4\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Starthaltestelle: Beverly Gardens Park<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-6 kt-pane1163_02d888-af\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Fahrplan Celebrity Homes Tour<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_25d44b-fd:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_25d44b-fd ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_25d44b-fd ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_25d44b-fd .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_25d44b-fd ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1163_25d44b-fd ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1163_25d44b-fd kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1163_69af09-bb .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_69af09-bb\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">T\u00e4gliche Abfahrten: 11:00\/ 13:30 und 16:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_65021a-ea .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_65021a-ea\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Dauer der Rundfahrt: 2 Stunden<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_11fa6a-95 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_11fa6a-95\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Starthaltestelle: Big Bus Visitor Centre Hollywood<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_aae981-bb .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_aae981-bb\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Separates Ticket erforderlich: <a href=\"https:\/\/www.tiqets.com\/de\/los-angeles-sehenswuerdigkeiten-c81810\/tickets-fur-l-a-celebrity-homes-tour-p1026876?partner=hopon\" target=\"_blank\" rel=\"noopener nofollow sponsored\" title=\"\">Ticket Celebrity Homes Tour<\/a><\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-7 kt-pane1163_7f6a3e-33\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">TCL Chinese Theatre Walking Tour<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4f45b6-c8:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4f45b6-c8 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4f45b6-c8 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4f45b6-c8 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4f45b6-c8 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1163_4f45b6-c8 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1163_4f45b6-c8 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1163_1a0e04-6c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_1a0e04-6c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Dauer: 30 Minuten<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_585a10-fd .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_585a10-fd\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Treffpunkt: TCL Chinese Theatre<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_c1862b-ec .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_c1862b-ec\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Separates Ticket erforderlich: <a href=\"https:\/\/www.tiqets.com\/de\/los-angeles-sehenswuerdigkeiten-c81810\/tickets-fur-l-a-celebrity-homes-tour-p1026876?partner=hopon\" target=\"_blank\" rel=\"noopener nofollow sponsored\" title=\"\"><a href=\"https:\/\/www.jdoqocy.com\/click-101037000-13625822?url=https%3A%2F%2Fwww.bigbustours.com%2Fen%2Flos-angeles%2Flos-angeles-attractions-tcl-chinese-theatre-vip-tour-tickets\" target=\"_blank\" rel=\"noopener nofollow sponsored\" title=\"\">Ticket TCL Chinese Theatre Tour<\/a><\/a><\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane1163_f9165c-4c\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Kontakt: Big Bus Los Angeles<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1163_7e5ff2-dc, .wp-block-kadence-advancedheading.kt-adv-heading1163_7e5ff2-dc[data-kb-block=\"kb-adv-heading1163_7e5ff2-dc\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1163_7e5ff2-dc mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1163_7e5ff2-dc[data-kb-block=\"kb-adv-heading1163_7e5ff2-dc\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1163_7e5ff2-dc img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1163_7e5ff2-dc[data-kb-block=\"kb-adv-heading1163_7e5ff2-dc\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1163_7e5ff2-dc wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1163_7e5ff2-dc\">Sollten Sie Fragen an das Unternehmen haben oder sich beschweren wollen, k\u00f6nnen Sie Big Bus Los Angeles \u00fcber folgendes Kontaktformular erreichen:<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_9448cb-5c:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_9448cb-5c ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_9448cb-5c ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_9448cb-5c .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_9448cb-5c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1163_9448cb-5c ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1163_9448cb-5c kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1163_8e974f-be .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_8e974f-be\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mail kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M4 4h16c1.1 0 2 .9 2 2v12c0 1.1-.9 2-2 2H4c-1.1 0-2-.9-2-2V6c0-1.1.9-2 2-2z\"\/><polyline points=\"22,6 12,13 2,6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/www.bigbustours.com\/en\/los-angeles\/contact-us?utm_source=Commission_Junction&amp;utm_medium=Affiliate_Marketing&amp;utm_campaign=Patrick+K%C3%BChne_101037000&amp;cjevent=76c29190094b11f0819302970a18b8f6\" target=\"_blank\" rel=\"noopener\" title=\"\">Kontaktformular<\/a><\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1163_873593-d8, .wp-block-kadence-advancedheading.kt-adv-heading1163_873593-d8[data-kb-block=\"kb-adv-heading1163_873593-d8\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1163_873593-d8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1163_873593-d8[data-kb-block=\"kb-adv-heading1163_873593-d8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1163_873593-d8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1163_873593-d8[data-kb-block=\"kb-adv-heading1163_873593-d8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1163_873593-d8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1163_873593-d8\">Wenn Sie Fragen zur Ticketbuchung haben, wenden Sie sich bitte an den Kundenservice von Tiqets.com oder GetYourGuide (je nachdem, wo Sie Ihr Ticket gebucht haben).<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">An Bord gibt es einen mehrsprachigen Audioguide. Mit der Big Bus App k\u00f6nnen Sie die Busse live verfolgen.<\/p>\n\n\n<p><strong>Ticketg\u00fcltigkeit:<\/strong> 1-2 Tage<br \/>\n<strong>Bewertung:<\/strong> 2,9 (8 Reviews)<br \/>\n<strong>Preis:<\/strong> ab $59.00<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns1163_4e21cd-e7{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns1163_4e21cd-e7 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1163_4e21cd-e7 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1163_4e21cd-e7 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1163_4e21cd-e7 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1163_4e21cd-e7 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1163_4e21cd-e7 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1163_4e21cd-e7 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1163_4e21cd-e7 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1163_4e21cd-e7\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1163_f5dc14-62.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1163_f5dc14-62.kb-button{color:var(--base-3);background:#e51b22;box-shadow:2px 2px 2px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn1163_f5dc14-62.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1163_f5dc14-62.kb-button:focus{color:var(--base-3);background:#b51310;}<\/style><a class=\"kb-button kt-button button kb-btn1163_f5dc14-62 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/www.tiqets.com\/de\/checkout\/tickets-fur-hop-on-hop-off-bus-los-angeles-p1009752\/booking_details\/?partner=hopon\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_externalLink kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Tickets kaufen<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1163_6fd8cd-ff, .wp-block-kadence-advancedheading.kt-adv-heading1163_6fd8cd-ff[data-kb-block=\"kb-adv-heading1163_6fd8cd-ff\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1163_6fd8cd-ff mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1163_6fd8cd-ff[data-kb-block=\"kb-adv-heading1163_6fd8cd-ff\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1163_6fd8cd-ff img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1163_6fd8cd-ff[data-kb-block=\"kb-adv-heading1163_6fd8cd-ff\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1163_6fd8cd-ff wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1163_6fd8cd-ff\">Wenn Sie Ihr Ticket online kaufen, erhalten Sie anschlie\u00dfend einen Voucher, den Sie auf Ihrem Handy speichern k\u00f6nnen. Zeigen Sie diesen Voucher dem Buspersonal bei der ersten Fahrt. Ihr Ticket ist dann 1 oder 2 Tage g\u00fcltig.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1163_d1a3be-fc{margin-bottom:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);}.kb-row-layout-id1163_d1a3be-fc > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1163_d1a3be-fc > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1163_d1a3be-fc > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1163_d1a3be-fc > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1163_d1a3be-fc > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1163_d1a3be-fc > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1163_d1a3be-fc alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1163_01d4b4-3f > .kt-inside-inner-col,.kadence-column1163_01d4b4-3f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_01d4b4-3f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_01d4b4-3f > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_01d4b4-3f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_01d4b4-3f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_01d4b4-3f{position:relative;}@media all and (max-width: 1024px){.kadence-column1163_01d4b4-3f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_01d4b4-3f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_01d4b4-3f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1163_2b249e-e3, .wp-block-kadence-advancedheading.kt-adv-heading1163_2b249e-e3[data-kb-block=\"kb-adv-heading1163_2b249e-e3\"]{text-align:center;font-style:normal;background-color:#b51310;border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}.wp-block-kadence-advancedheading.kt-adv-heading1163_2b249e-e3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1163_2b249e-e3[data-kb-block=\"kb-adv-heading1163_2b249e-e3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1163_2b249e-e3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1163_2b249e-e3[data-kb-block=\"kb-adv-heading1163_2b249e-e3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1163_2b249e-e3, .wp-block-kadence-advancedheading.kt-adv-heading1163_2b249e-e3[data-kb-block=\"kb-adv-heading1163_2b249e-e3\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1163_2b249e-e3, .wp-block-kadence-advancedheading.kt-adv-heading1163_2b249e-e3[data-kb-block=\"kb-adv-heading1163_2b249e-e3\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}<\/style>\n<h2 id=\"0-valencia-bus-tur%C3%ADstic\" class=\"kt-adv-heading1163_2b249e-e3 wp-block-kadence-advancedheading has-base-3-color has-text-color\" data-kb-block=\"kb-adv-heading1163_2b249e-e3\">Star Line Tours<\/h2>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1163_db0fe1-d2{margin-bottom:0px;}.kb-row-layout-id1163_db0fe1-d2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1163_db0fe1-d2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1163_db0fe1-d2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1163_db0fe1-d2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1163_db0fe1-d2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1163_db0fe1-d2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1163_db0fe1-d2 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1163_c512c6-ca > .kt-inside-inner-col,.kadence-column1163_c512c6-ca > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_c512c6-ca > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_c512c6-ca > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_c512c6-ca > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_c512c6-ca > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_c512c6-ca{position:relative;}@media all and (max-width: 1024px){.kadence-column1163_c512c6-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_c512c6-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_c512c6-ca\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1163_ec7d01-40 > .kt-inside-inner-col,.kadence-column1163_ec7d01-40 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_ec7d01-40 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_ec7d01-40 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_ec7d01-40 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_ec7d01-40 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_ec7d01-40{position:relative;}.kadence-column1163_ec7d01-40, .kt-inside-inner-col > .kadence-column1163_ec7d01-40:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column1163_ec7d01-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_ec7d01-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_ec7d01-40\"><div class=\"kt-inside-inner-col\">\n<div data-tiqets-widget=\"availability\" data-layout=\"full\" data-orientation=\"horizontal\" data-product-id=\"1057560\" data-partner=\"hopon\"><\/div>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1163_d98059-01, .wp-block-kadence-advancedheading.kt-adv-heading1163_d98059-01[data-kb-block=\"kb-adv-heading1163_d98059-01\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1163_d98059-01 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1163_d98059-01[data-kb-block=\"kb-adv-heading1163_d98059-01\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1163_d98059-01 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1163_d98059-01[data-kb-block=\"kb-adv-heading1163_d98059-01\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p id=\"1-valencia-bus-turistic-bietet-seit-1999-stadtrundfahrten-an-die-roten-hop-onhop-off-busse-bedienen-haltestellen-die-%C3%BCber-ganz-valencia-verteilt-sind-an-bord-gibt-es-einen-audioguide-in-10-sprachen\" class=\"kt-adv-heading1163_d98059-01 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1163_d98059-01\">Star Line Tours bietet seine Touren in Los Angeles in Kooperation mit dem Unternehmen City Sightseeing an.<\/p>\n\n\n<style>.kadence-column1163_6bba10-d9 > .kt-inside-inner-col,.kadence-column1163_6bba10-d9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_6bba10-d9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_6bba10-d9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_6bba10-d9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_6bba10-d9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_6bba10-d9{position:relative;}.kadence-column1163_6bba10-d9, .kt-inside-inner-col > .kadence-column1163_6bba10-d9:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column1163_6bba10-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_6bba10-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_6bba10-d9\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id1163_4c699b-30 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:5px;}.kt-accordion-id1163_4c699b-30 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id1163_4c699b-30 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:var(--contrast);padding-top:10px;padding-right:14px;padding-bottom:10px;padding-left:14px;}.kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--contrast);}.kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--contrast);}.kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id1163_4c699b-30 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1163_4c699b-30 .kt-blocks-accordion-header:focus-visible{color:#444444;background:var(--base-2);border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--base-2);}.kt-accordion-id1163_4c699b-30 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1163_4c699b-30 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#e51b22;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1163_4c699b-30:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#e51b22;}@media all and (max-width: 1024px){.kt-accordion-id1163_4c699b-30 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id1163_4c699b-30 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id1163_4c699b-30 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1163_4c699b-30 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id1163_4c699b-30 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1163_4c699b-30 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id1163_4c699b-30 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id1163_4c699b-30 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:5px;}.kt-accordion-id1163_4c699b-30 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id1163_4c699b-30 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id1163_4c699b-30 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1163_4c699b-30 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id1163_4c699b-30 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1163_4c699b-30 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id1163_4c699b-30 kt-accordion-has-8-panes kt-active-pane-3 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane1163_a6dbeb-74\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Routen &amp; Haltestellen<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_f99817-0f:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_f99817-0f ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_f99817-0f ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_f99817-0f .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_f99817-0f ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1163_f99817-0f ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1163_f99817-0f kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1163_f1dcbe-3b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_f1dcbe-3b\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">3 Routen \u2013&nbsp;40+ Haltestellen<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_8306c1-7d .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_8306c1-7d\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/starlinetours.com\/en\/map\" target=\"_blank\" rel=\"noopener\" title=\"\">Karte mit Route &amp; Haltestellen<\/a><\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane1163_9d0fd2-90\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Fahrplan Rote Linie\/ Hollywood<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_f94506-de:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_f94506-de ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_f94506-de ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_f94506-de .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_f94506-de ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1163_f94506-de ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1163_f94506-de kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1163_01e1dc-5e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_01e1dc-5e\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Erste Abfahrt: 10:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_500c21-51 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_500c21-51\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Letzte Abfahrt: 16:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_5c6443-1f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_5c6443-1f\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Dauer der Rundfahrt: 2 Stunden<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_a3d4e3-02 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_a3d4e3-02\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Starthaltestelle: Dolby Theatre (Starline Terminal)<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane1163_a7cb15-26\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Fahrplan Gelbe Linie\/ Santa Monica<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4e3518-fb:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4e3518-fb ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4e3518-fb ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4e3518-fb .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_4e3518-fb ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1163_4e3518-fb ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1163_4e3518-fb kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1163_c3237f-c9 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_c3237f-c9\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Erste Abfahrt: 10:20<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_5cf383-41 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_5cf383-41\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Letzte Abfahrt: 16:25<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_03157a-e7 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_03157a-e7\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Dauer der Rundfahrt: 45 Minuten<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_c30a4b-6a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_c30a4b-6a\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Starthaltestelle: Beverly Hills<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-6 kt-pane1163_0b67e7-a8\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Fahrplan Lila Linie\/ Downtown<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_40383c-fb:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_40383c-fb ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_40383c-fb ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_40383c-fb .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_40383c-fb ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1163_40383c-fb ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1163_40383c-fb kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1163_922ffb-ac .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_922ffb-ac\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Erste Abfahrt: 10:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_8e674e-89 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_8e674e-89\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Letzte Abfahrt: 14:30<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_2c30ca-74 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_2c30ca-74\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Dauer der Rundfahrt: 2 Stunden<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_b9830e-59 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_b9830e-59\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Starthaltestelle: Dolby Theatre<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-8 kt-pane1163_d77eca-da\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Fahrplan Blaue Linie\/ Hollywood<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_ef8587-2e:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_ef8587-2e ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_ef8587-2e ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_ef8587-2e .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_ef8587-2e ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1163_ef8587-2e ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1163_ef8587-2e kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1163_e68634-84 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_e68634-84\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Erste Abfahrt: 09:30<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_bafa0d-54 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_bafa0d-54\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Letzte Abfahrt: 16:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_354a73-22 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_354a73-22\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Dauer der Rundfahrt: 60 Minuten<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_e54907-6f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_e54907-6f\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Starthaltestelle: Dolby Theatre<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane1163_fafbd4-70\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Kontakt: Star Line Tours<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1163_e16eff-26, .wp-block-kadence-advancedheading.kt-adv-heading1163_e16eff-26[data-kb-block=\"kb-adv-heading1163_e16eff-26\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1163_e16eff-26 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1163_e16eff-26[data-kb-block=\"kb-adv-heading1163_e16eff-26\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1163_e16eff-26 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1163_e16eff-26[data-kb-block=\"kb-adv-heading1163_e16eff-26\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1163_e16eff-26 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1163_e16eff-26\">Sollten Sie Fragen an das Unternehmen haben oder sich beschweren wollen, k\u00f6nnen Sie Star Line Tours telefonisch oder per E-Mail erreichen:<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e2c563-96:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e2c563-96 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e2c563-96 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e2c563-96 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e2c563-96 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1163_e2c563-96 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1163_e2c563-96 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1163_1fd451-1f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_1fd451-1f\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mail kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M4 4h16c1.1 0 2 .9 2 2v12c0 1.1-.9 2-2 2H4c-1.1 0-2-.9-2-2V6c0-1.1.9-2 2-2z\"\/><polyline points=\"22,6 12,13 2,6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">info@starlinetours.com<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_ee00ed-74 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_ee00ed-74\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_phone kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 16.92v3a2 2 0 0 1-2.18 2 19.79 19.79 0 0 1-8.63-3.07 19.5 19.5 0 0 1-6-6 19.79 19.79 0 0 1-3.07-8.67A2 2 0 0 1 4.11 2h3a2 2 0 0 1 2 1.72 12.84 12.84 0 0 0 .7 2.81 2 2 0 0 1-.45 2.11L8.09 9.91a16 16 0 0 0 6 6l1.27-1.27a2 2 0 0 1 2.11-.45 12.84 12.84 0 0 0 2.81.7A2 2 0 0 1 22 16.92z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">+1 (323) 463-3333<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1163_3bd218-34, .wp-block-kadence-advancedheading.kt-adv-heading1163_3bd218-34[data-kb-block=\"kb-adv-heading1163_3bd218-34\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1163_3bd218-34 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1163_3bd218-34[data-kb-block=\"kb-adv-heading1163_3bd218-34\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1163_3bd218-34 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1163_3bd218-34[data-kb-block=\"kb-adv-heading1163_3bd218-34\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1163_3bd218-34 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1163_3bd218-34\">Wenn Sie Fragen zur Ticketbuchung haben, wenden Sie sich bitte an den Kundenservice von Tiqets.com oder GetYourGuide (je nachdem, wo Sie Ihr Ticket gebucht haben).<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">An Bord gibt es einen Audioguide in 9 Sprachen.<\/p>\n\n\n<p><strong>Ticketg\u00fcltigkeit:<\/strong> 24-72 Stunden<br \/>\n<strong>Bewertung:<\/strong> 3,8 (33 Reviews)<br \/>\n<strong>Preis:<\/strong> ab $57.00<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns1163_ad5765-b4{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns1163_ad5765-b4 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1163_ad5765-b4 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1163_ad5765-b4 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1163_ad5765-b4 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1163_ad5765-b4 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1163_ad5765-b4 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1163_ad5765-b4 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1163_ad5765-b4 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1163_ad5765-b4\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1163_aa7977-e5.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1163_aa7977-e5.kb-button{color:var(--base-3);background:#e51b22;box-shadow:2px 2px 2px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn1163_aa7977-e5.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1163_aa7977-e5.kb-button:focus{color:var(--base-3);background:#b51310;}<\/style><a class=\"kb-button kt-button button kb-btn1163_aa7977-e5 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/www.tiqets.com\/de\/checkout\/tickets-fur-los-angeles-and-hollywood-hop-on-hop-off-bus-p1057560\/booking_details\/?partner=hopon\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_externalLink kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Tickets kaufen<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1163_b6bd4f-76, .wp-block-kadence-advancedheading.kt-adv-heading1163_b6bd4f-76[data-kb-block=\"kb-adv-heading1163_b6bd4f-76\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1163_b6bd4f-76 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1163_b6bd4f-76[data-kb-block=\"kb-adv-heading1163_b6bd4f-76\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1163_b6bd4f-76 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1163_b6bd4f-76[data-kb-block=\"kb-adv-heading1163_b6bd4f-76\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1163_b6bd4f-76 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1163_b6bd4f-76\">Wenn Sie Ihr Ticket online kaufen, erhalten Sie anschlie\u00dfend einen Voucher, den Sie auf Ihrem Handy speichern k\u00f6nnen. Zeigen Sie diesen Voucher dem Buspersonal bei der ersten Fahrt. Ihr Ticket ist dann 24, 48 oder 72 Stunden g\u00fcltig.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1163_70de49-43{margin-bottom:0px;margin-bottom:var(--global-kb-spacing-md, 2rem);}.kb-row-layout-id1163_70de49-43 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1163_70de49-43 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1163_70de49-43 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1163_70de49-43 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1163_70de49-43 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1163_70de49-43 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1163_70de49-43 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1163_7a6322-d5 > .kt-inside-inner-col,.kadence-column1163_7a6322-d5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_7a6322-d5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_7a6322-d5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_7a6322-d5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_7a6322-d5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_7a6322-d5{position:relative;}@media all and (max-width: 1024px){.kadence-column1163_7a6322-d5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_7a6322-d5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_7a6322-d5\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1163_985711-ff, .wp-block-kadence-advancedheading.kt-adv-heading1163_985711-ff[data-kb-block=\"kb-adv-heading1163_985711-ff\"]{font-style:normal;background-color:#b51310;border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}.wp-block-kadence-advancedheading.kt-adv-heading1163_985711-ff mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1163_985711-ff[data-kb-block=\"kb-adv-heading1163_985711-ff\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1163_985711-ff img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1163_985711-ff[data-kb-block=\"kb-adv-heading1163_985711-ff\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1163_985711-ff, .wp-block-kadence-advancedheading.kt-adv-heading1163_985711-ff[data-kb-block=\"kb-adv-heading1163_985711-ff\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1163_985711-ff, .wp-block-kadence-advancedheading.kt-adv-heading1163_985711-ff[data-kb-block=\"kb-adv-heading1163_985711-ff\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}<\/style>\n<h2 id=\"11-hop-onhop-off-sehensw%C3%BCrdigkeiten\" class=\"kt-adv-heading1163_985711-ff wp-block-kadence-advancedheading has-base-3-color has-text-color\" data-kb-block=\"kb-adv-heading1163_985711-ff\">Hop-on\/Hop-off: Sehensw\u00fcrdigkeiten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los Angeles ist f\u00fcr viele Sehensw\u00fcrdigkeiten bekannt. Allem voran nat\u00fcrlich f\u00fcr Hollywood. Die meisten Attraktionen dieser schillernden Metropole k\u00f6nnen Sie bei einer Stadtrundfahrt mit dem Hop-on\/Hop-off-Bus erreichen:<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e4f924-c4:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e4f924-c4 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e4f924-c4 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e4f924-c4 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e4f924-c4 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1163_e4f924-c4 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}@media all and (min-width: 1025px){.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e4f924-c4:not(.kt-svg-icon-list-columns-1) ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap:not(:last-child){margin:0px;}}@media all and (min-width: 768px) and (max-width: 1024px){.wp-block-kadence-iconlist.kt-svg-icon-list-items1163_e4f924-c4:not(.kt-tablet-svg-icon-list-columns-1) ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap:not(:last-child){margin:0px;}}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1163_e4f924-c4 kt-svg-icon-list-columns-2 alignnone kt-mobile-svg-icon-list-columns-1\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1163_e1381e-6e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_e1381e-6e\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Walk of Fame<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_4e68a7-f4 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_4e68a7-f4\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">L. A. County Museum of Art<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_5279d7-c2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_5279d7-c2\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Hollywood Sign<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_e1732f-a7 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_e1732f-a7\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TCL Chinese Theatre<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_e3699b-05 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_e3699b-05\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Disneyland Resort<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_80a5ad-3a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_80a5ad-3a\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Venice Beach<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_4666b7-f7 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_4666b7-f7\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Santa Monica Pier<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_0017fa-e7 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_0017fa-e7\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Universal Studios<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_2c13ea-93 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_2c13ea-93\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Grand Central Market<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1163_e3ee78-f3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1163_e3ee78-f3\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Rodeo Drive<\/span><\/li>\n<\/ul><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Steigen Sie einfach an der n\u00e4chsten Haltestelle aus und besuchen Sie die Sehensw\u00fcrdigkeiten auf Ihrer Wunschliste. Nicht alle Attraktionen haben eine eigene Haltestelle. Planen Sie daher einige Minuten Fu\u00dfweg ein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Hollywood Sign und die Universal Studios sind mit dem Hop-on-Hop-off-Bus nicht erreichbar.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns1163_75035d-51{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns1163_75035d-51 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1163_75035d-51 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1163_75035d-51 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1163_75035d-51 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1163_75035d-51 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1163_75035d-51 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1163_75035d-51 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1163_75035d-51 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1163_75035d-51\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1163_406628-71.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1163_406628-71.kb-button{color:var(--base-3);background:#e51b22;box-shadow:2px 2px 2px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn1163_406628-71.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1163_406628-71.kb-button:focus{color:var(--base-3);background:#b51310;}<\/style><a class=\"kb-button kt-button button kb-btn1163_406628-71 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/www.tiqets.com\/de\/checkout\/tickets-fur-hop-on-hop-off-bus-los-angeles-p1009752\/booking_details\/?partner=hopon\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_externalLink kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Tickets kaufen<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1163_7564f8-91{margin-bottom:0px;margin-bottom:var(--global-kb-spacing-md, 2rem);}.kb-row-layout-id1163_7564f8-91 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1163_7564f8-91 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1163_7564f8-91 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1163_7564f8-91 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1163_7564f8-91 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1163_7564f8-91 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1163_7564f8-91 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1163_d625b6-b3 > .kt-inside-inner-col,.kadence-column1163_d625b6-b3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_d625b6-b3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_d625b6-b3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_d625b6-b3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_d625b6-b3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_d625b6-b3{position:relative;}@media all and (max-width: 1024px){.kadence-column1163_d625b6-b3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_d625b6-b3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_d625b6-b3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1163_b63fbb-df, .wp-block-kadence-advancedheading.kt-adv-heading1163_b63fbb-df[data-kb-block=\"kb-adv-heading1163_b63fbb-df\"]{font-style:normal;background-color:#b51310;border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}.wp-block-kadence-advancedheading.kt-adv-heading1163_b63fbb-df mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1163_b63fbb-df[data-kb-block=\"kb-adv-heading1163_b63fbb-df\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1163_b63fbb-df img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1163_b63fbb-df[data-kb-block=\"kb-adv-heading1163_b63fbb-df\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1163_b63fbb-df, .wp-block-kadence-advancedheading.kt-adv-heading1163_b63fbb-df[data-kb-block=\"kb-adv-heading1163_b63fbb-df\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1163_b63fbb-df, .wp-block-kadence-advancedheading.kt-adv-heading1163_b63fbb-df[data-kb-block=\"kb-adv-heading1163_b63fbb-df\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}<\/style>\n<h2 id=\"5-kombitickets\" class=\"kt-adv-heading1163_b63fbb-df wp-block-kadence-advancedheading has-base-3-color has-text-color\" data-kb-block=\"kb-adv-heading1163_b63fbb-df\">Kombitickets: Bus &amp; Attraktion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mit den folgenden Kombitickets k\u00f6nnen Sie eine Stadtrundfahrt im Bus machen und eine oder mehrere Attraktionen besichtigen. Bei vielen Kombitickets sparen Sie etwas Geld.<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1163_e67e40-7e .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-1163_e67e40-7e .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1163_e67e40-7e\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n<style>.kt-tabs-id1163_2ca232-a6 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid #0a6689;border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);background:var(--global-palette9, #ffffff);}.wp-block-kadence-tabs .kt-tabs-id1163_2ca232-a6 > .kt-tabs-title-list li{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id1163_2ca232-a6 > .kt-tabs-title-list li:last-child{margin-right:0px;}.wp-block-kadence-tabs .kt-tabs-id1163_2ca232-a6 > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id1163_2ca232-a6 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{line-height:1.4em;font-weight:regular;font-style:normal;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:8px;padding-right:20px;padding-bottom:8px;padding-left:20px;border-color:var(--global-palette7, #eeeeee);color:var(--base-3);background:var(--contrast-2);}.wp-block-kadence-tabs .kt-tabs-id1163_2ca232-a6 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id1163_2ca232-a6 > .kt-tabs-title-list li .kt-tab-title:hover, .wp-block-kadence-tabs .kt-tabs-id1163_2ca232-a6 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title:hover{border-color:var(--global-palette7, #eeeeee);color:var(--base-3);background:#b51310;}.wp-block-kadence-tabs .kt-tabs-id1163_2ca232-a6 > .kt-tabs-title-list li.kt-tab-title-active .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id1163_2ca232-a6 > .kt-tabs-content-wrap > .kt-tabs-accordion-title.kt-tab-title-active .kt-tab-title{border-color:var(--global-palette7, #eeeeee);color:#ffffff;background:#b51310;}@media all and (max-width: 1024px){.kt-tabs-id1163_2ca232-a6 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid #0a6689;border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;}}@media all and (max-width: 767px){.kt-tabs-id1163_2ca232-a6 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid #0a6689;border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;}}<\/style>\n<div class=\"wp-block-kadence-tabs alignnone\"><div class=\"kt-tabs-wrap kt-tabs-id1163_2ca232-a6 kt-tabs-has-2-tabs kt-active-tab-1 kt-tabs-layout-tabs kt-tabs-tablet-layout-inherit kt-tabs-mobile-layout-inherit kt-tab-alignment-left \"><ul class=\"kt-tabs-title-list\"><li id=\"tab-warnerbrosstudiotour\" class=\"kt-title-item kt-title-item-1 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-active\"><a href=\"#tab-warnerbrosstudiotour\" data-tab=\"1\" class=\"kt-tab-title kt-tab-title-1 \"><span class=\"kt-title-text\">Warner Bros. Studio Tour<\/span><\/a><\/li><li id=\"tab-madametussauds\" class=\"kt-title-item kt-title-item-2 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-madametussauds\" data-tab=\"2\" class=\"kt-tab-title kt-tab-title-2 \"><span class=\"kt-title-text\">Madame Tussauds<\/span><\/a><\/li><\/ul><div class=\"kt-tabs-content-wrap\">\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-1 kt-inner-tab321db6-6c\"><div class=\"kt-tab-inner-content-inner\"><div class=\"gb-container gb-container-42ab9dab\">\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1163_77bb16-54{margin-bottom:0px;}.kb-row-layout-id1163_77bb16-54 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1163_77bb16-54 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1163_77bb16-54 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}.kb-row-layout-id1163_77bb16-54 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1163_77bb16-54 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id1163_77bb16-54 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1163_77bb16-54 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1163_ad963d-41 > .kt-inside-inner-col,.kadence-column1163_ad963d-41 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_ad963d-41 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_ad963d-41 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_ad963d-41 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_ad963d-41 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_ad963d-41{position:relative;}@media all and (max-width: 1024px){.kadence-column1163_ad963d-41 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_ad963d-41 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_ad963d-41\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"478\" src=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-warner-brother-studios.jpg\" alt=\"Los Angeles: Warner Bros. Studios\" class=\"wp-image-1182\" srcset=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-warner-brother-studios.jpg 800w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-warner-brother-studios-300x179.jpg 300w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-warner-brother-studios-768x459.jpg 768w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-warner-brother-studios-18x12.jpg 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\">\u00a9 Julie May\/ Unsplash<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column1163_9d64a2-19 > .kt-inside-inner-col,.kadence-column1163_9d64a2-19 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_9d64a2-19 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_9d64a2-19 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_9d64a2-19 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_9d64a2-19 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_9d64a2-19{position:relative;}@media all and (max-width: 1024px){.kadence-column1163_9d64a2-19 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_9d64a2-19 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_9d64a2-19\"><div class=\"kt-inside-inner-col\">\n<h4 class=\"gb-headline gb-headline-ccf07b39 gb-headline-text\" id=\"4-hop-onhop-off-sagrada-fam%C3%ADlia\">Hop-on\/Hop-off + Warner Bros. Studio Tour<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Machen Sie eine Stadtrundfahrt im Hop-on\/Hop-off-Bus (Big Bus) und besuchen Sie die Warner Bros. Studios. Sie erhalten alle Tickets sofort auf Ihr Mobiltelefon.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns1163_55169a-2f{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns1163_55169a-2f .kt-button{font-weight:normal;font-style:normal;}.kt-btns1163_55169a-2f .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1163_55169a-2f .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1163_55169a-2f .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1163_55169a-2f .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1163_55169a-2f .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1163_55169a-2f .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1163_55169a-2f .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1163_55169a-2f\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1163_6279f6-f9.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1163_6279f6-f9.kb-button{color:var(--base-3);background:#b51310;box-shadow:2px 2px 2px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn1163_6279f6-f9.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1163_6279f6-f9.kb-button:focus{color:var(--base-3);background:#b51310;}<\/style><a class=\"kb-button kt-button button kb-btn1163_6279f6-f9 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/www.bigbustours.com\/en\/los-angeles\/los-angeles-attractions-warner-bros-standard-studio-tour-tickets?utm_source=Commission_Junction&#038;utm_medium=Affiliate_Marketing&#038;utm_campaign=Patrick+K%C3%BChne_101037000&#038;cjevent=ac6f7f38094f11f083c4028e0a18ba72\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_externalLink kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Tickets kaufen<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-2 kt-inner-tab0036ec-ea\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1163_544308-ae{margin-bottom:0px;}.kb-row-layout-id1163_544308-ae > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1163_544308-ae > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1163_544308-ae > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}.kb-row-layout-id1163_544308-ae > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1163_544308-ae > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id1163_544308-ae > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1163_544308-ae alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1163_85e007-c1 > .kt-inside-inner-col,.kadence-column1163_85e007-c1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_85e007-c1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_85e007-c1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_85e007-c1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_85e007-c1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_85e007-c1{position:relative;}@media all and (max-width: 1024px){.kadence-column1163_85e007-c1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_85e007-c1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_85e007-c1\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"501\" src=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-madame-tussauds.jpg\" alt=\"Madame Tussauds in Los Angeles\" class=\"wp-image-1183\" srcset=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-madame-tussauds.jpg 800w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-madame-tussauds-300x188.jpg 300w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-madame-tussauds-768x481.jpg 768w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/los-angeles-madame-tussauds-18x12.jpg 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\">\u00a9 Mathew Browne\/ Unsplash<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column1163_81bf55-c3 > .kt-inside-inner-col,.kadence-column1163_81bf55-c3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_81bf55-c3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_81bf55-c3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_81bf55-c3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_81bf55-c3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_81bf55-c3{position:relative;}@media all and (max-width: 1024px){.kadence-column1163_81bf55-c3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_81bf55-c3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_81bf55-c3\"><div class=\"kt-inside-inner-col\">\n<h4 class=\"gb-headline gb-headline-5f3ecfbd gb-headline-text\" id=\"4-hop-onhop-off-sagrada-fam%C3%ADlia\">Hop-on\/Hop-off + Madame Tussauds<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Machen Sie eine Stadtrundfahrt im Hop-on\/Hop-off-Bus (Big Bus) und besuchen Sie Madame Tussauds. Sie erhalten beide Tickets sofort auf Ihr Mobiltelefon.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns1163_073b91-ba{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns1163_073b91-ba .kt-button{font-weight:normal;font-style:normal;}.kt-btns1163_073b91-ba .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1163_073b91-ba .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1163_073b91-ba .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1163_073b91-ba .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1163_073b91-ba .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1163_073b91-ba .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1163_073b91-ba .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1163_073b91-ba\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1163_a77d82-b9.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1163_a77d82-b9.kb-button{color:var(--base-3);background:#b51310;box-shadow:2px 2px 2px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn1163_a77d82-b9.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1163_a77d82-b9.kb-button:focus{color:var(--base-3);background:#b51310;}<\/style><a class=\"kb-button kt-button button kb-btn1163_a77d82-b9 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/www.kqzyfj.com\/click-101037000-13625822?url=https%3A%2F%2Fwww.bigbustours.com%2Fen%2Flos-angeles%2Flos-angeles-discover-ticket-plus-madame-tussauds\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_externalLink kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Tickets kaufen<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1163_01435e-10{margin-bottom:0px;}.kb-row-layout-id1163_01435e-10 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1163_01435e-10 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1163_01435e-10 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1163_01435e-10 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1163_01435e-10 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1163_01435e-10 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1163_01435e-10 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1163_2c1c05-14 > .kt-inside-inner-col,.kadence-column1163_2c1c05-14 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1163_2c1c05-14 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1163_2c1c05-14 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1163_2c1c05-14 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1163_2c1c05-14 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1163_2c1c05-14{position:relative;}@media all and (max-width: 1024px){.kadence-column1163_2c1c05-14 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1163_2c1c05-14 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1163_2c1c05-14\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1163_25e216-4d, .wp-block-kadence-advancedheading.kt-adv-heading1163_25e216-4d[data-kb-block=\"kb-adv-heading1163_25e216-4d\"]{font-style:normal;background-color:#b51310;border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}.wp-block-kadence-advancedheading.kt-adv-heading1163_25e216-4d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1163_25e216-4d[data-kb-block=\"kb-adv-heading1163_25e216-4d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1163_25e216-4d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1163_25e216-4d[data-kb-block=\"kb-adv-heading1163_25e216-4d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1163_25e216-4d, .wp-block-kadence-advancedheading.kt-adv-heading1163_25e216-4d[data-kb-block=\"kb-adv-heading1163_25e216-4d\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1163_25e216-4d, .wp-block-kadence-advancedheading.kt-adv-heading1163_25e216-4d[data-kb-block=\"kb-adv-heading1163_25e216-4d\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}<\/style>\n<h2 id=\"12-lohnt-sich-eine-valencia-stadtrundfahrt\" class=\"kt-adv-heading1163_25e216-4d wp-block-kadence-advancedheading has-base-3-color has-text-color\" data-kb-block=\"kb-adv-heading1163_25e216-4d\">Lohnt sich eine Los Angeles-Stadtrundfahrt?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los Angeles ist eine unglaublich vielf\u00e4ltige Stadt, in der es viel zu entdecken gibt. Nutzen Sie das gut organisierte System der Hop-on-Hop-off-Busse mit verschiedenen Routen und zahlreichen Haltestellen, um die Stadt bequem und flexibel zu erkunden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Hop-on-Hop-off-Konzept bietet Ihnen maximale Flexibilit\u00e4t. Sie k\u00f6nnen an jeder beliebigen Haltestelle aus- und wieder einsteigen. So k\u00f6nnen Sie Los Angeles in Ihrem eigenen Tempo erkunden, ohne sich an starre Zeitpl\u00e4ne halten zu m\u00fcssen. Gerade in einer Metropole wie Los Angeles, die sich \u00fcber ein sehr gro\u00dfes Gebiet erstreckt und viele Sehensw\u00fcrdigkeiten zu bieten hat, ist diese Flexibilit\u00e4t besonders wertvoll.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein gro\u00dfer Pluspunkt ist auch die fl\u00e4chendeckende Versorgung mit Haltestellen in der Stadt. Die Busse halten an den wichtigsten Sehensw\u00fcrdigkeiten wie dem Hollywood Walk of Fame, dem Rodeo Drive, dem Santa Monica Pier und vielen mehr. So k\u00f6nnen Sie sicher sein, dass Sie die meisten Sehensw\u00fcrdigkeiten der Stadt sehen, ohne sich um komplizierte Routenplanungen k\u00fcmmern zu m\u00fcssen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au\u00dferdem bietet der Hop-on-Hop-off-Bus einen erstklassigen Panoramablick auf die Attraktionen von Los Angeles. Die offene Gestaltung des Decks und die erh\u00f6hte Position im Bus erm\u00f6glichen es den G\u00e4sten, die faszinierende Stadt in vollen Z\u00fcgen zu genie\u00dfen.<\/p>\n\n\n<style>.kb-image1163_29313e-ed .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1163_29313e-ed size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off-6.jpg\" alt=\"Hop-on\/Hop-off-Bus\" class=\"kb-img wp-image-272\" srcset=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off-6.jpg 800w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off-6-300x188.jpg 300w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off-6-768x480.jpg 768w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off-6-18x12.jpg 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>\u00a9 Syda Productions \/ Shutterstock.com<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Die Hop-on-Hop-off-Busse bieten oft auch mehrsprachige Audiokommentare mit informativen Hintergrundinformationen zu Sehensw\u00fcrdigkeiten und zur Stadtgeschichte. So wird die Fahrt nicht nur unterhaltsam, sondern auch lehrreich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alles in allem ist eine Stadtrundfahrt mit dem Hop-on-Hop-off-Bus in Los Angeles eine bequeme, flexible und informative Art, die Sch\u00f6nheit und Vielfalt dieser faszinierenden Stadt zu erkunden. Es ist die ideale Option f\u00fcr Reisende, die das Beste aus ihrer Zeit in Los Angeles machen wollen, ohne viel Zeit mit Planung und Organisation verbringen zu m\u00fcssen.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns1163_5c8a56-e0{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns1163_5c8a56-e0 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1163_5c8a56-e0 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1163_5c8a56-e0 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1163_5c8a56-e0 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1163_5c8a56-e0 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1163_5c8a56-e0 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1163_5c8a56-e0 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1163_5c8a56-e0 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1163_5c8a56-e0\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1163_450758-fe.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1163_450758-fe.kb-button{color:var(--base-3);background:#e51b22;box-shadow:2px 2px 2px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn1163_450758-fe.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1163_450758-fe.kb-button:focus{color:var(--base-3);background:#b51310;}<\/style><a class=\"kb-button kt-button button kb-btn1163_450758-fe kt-btn-size-large kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/www.tiqets.com\/de\/checkout\/tickets-fur-hop-on-hop-off-bus-los-angeles-p1009752\/booking_details\/?partner=hopon\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_externalLink kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Tickets kaufen<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Itt tal\u00e1l inform\u00e1ci\u00f3kat a Los Angeles-i hop-on hop-off aut\u00f3buszos v\u00e1rosn\u00e9z\u0151 t\u00far\u00e1kr\u00f3l. T\u00e1j\u00e9koztatjuk a meg\u00e1ll\u00f3kr\u00f3l, a menetrendekr\u0151l \u00e9s az \u00e1rakr\u00f3l. A jegyeket k\u00f6zvetlen\u00fcl partnereinkn\u00e9l foglalhatja le, \u00e9s let\u00f6ltheti mobiltelefonj\u00e1ra. Az \u00e9rt\u00e9kes\u00edt\u00e9s\u00e9rt egy kis jutal\u00e9kot kapunk. Term\u00e9szetesen az \u00e1r az \u00d6n sz\u00e1m\u00e1ra v\u00e1ltozatlan marad. Big Bus Los Angeles Big Bus ... <a title=\"Los Angeles: Hop-on\/Hop-off\" class=\"read-more\" href=\"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/\" aria-label=\"Tov\u00e1bbi inform\u00e1ci\u00f3 err\u0151l: Los Angeles: Hop-on\/Hop-off\">Olvass tov\u00e1bb<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1163","page","type-page","status-publish"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hop-on\/Hop-off Los Angeles: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu 48 Stunden \u2713 30+ Haltestellen in Los Angeles. Jetzt informieren und Tickets kaufen.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"hu_HU\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Hop-on\/Hop-off.net -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los Angeles: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne 2026\" \/>\n\t\t<meta property=\"og:description\" content=\"Hop-on\/Hop-off Los Angeles: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu 48 Stunden \u2713 30+ Haltestellen in Los Angeles. Jetzt informieren und Tickets kaufen.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-11-16T14:04:51+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-28T09:16:02+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los Angeles: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne 2026\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hop-on\/Hop-off Los Angeles: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu 48 Stunden \u2713 30+ Haltestellen in Los Angeles. Jetzt informieren und Tickets kaufen.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\\\/los-angeles\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu#listItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\\\/los-angeles\\\/#listItem\",\"name\":\"Los Angeles: Hop-on\\\/Hop-off\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\\\/los-angeles\\\/#listItem\",\"position\":2,\"name\":\"Los Angeles: Hop-on\\\/Hop-off\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu#listItem\",\"name\":\"Startseite\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\\\/#organization\",\"name\":\"Hop-on\\\/Hop-off\",\"url\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/hop-on-hop-off.png\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\\\/los-angeles\\\/#organizationLogo\",\"width\":365,\"height\":70,\"caption\":\"Hop-on\\\/Hop-off Bus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\\\/los-angeles\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\\\/los-angeles\\\/#webpage\",\"url\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\\\/los-angeles\\\/\",\"name\":\"Los Angeles: Hop-on\\\/Hop-off - Routen & Fahrpl\\u00e4ne 2026\",\"description\":\"Hop-on\\\/Hop-off Los Angeles: \\u2713 Stadtrundfahrt im Bus \\u2713 Tickets f\\u00fcr bis zu 48 Stunden \\u2713 30+ Haltestellen in Los Angeles. Jetzt informieren und Tickets kaufen.\",\"inLanguage\":\"hu-HU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\\\/los-angeles\\\/#breadcrumblist\"},\"datePublished\":\"2023-11-16T14:04:51+00:00\",\"dateModified\":\"2026-04-28T09:16:02+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\\\/#website\",\"url\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\\\/\",\"name\":\"Hop-on\\\/Hop-off\",\"inLanguage\":\"hu-HU\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/hu\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Los Angeles: Hop-on\/Hop-off - \u00datvonalak \u00e9s menetrendek 2026","description":"Hop-on\/Hop-off Los Angeles: Jegyek ak\u00e1r 48 \u00f3r\u00e1ra \u2713 30+ meg\u00e1ll\u00f3 Los Angelesben. Tudjon meg t\u00f6bbet \u00e9s v\u00e1s\u00e1roljon jegyet most.","canonical_url":"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.hop-on-hop-off.net\/hu#listItem","position":1,"name":"Startseite","item":"https:\/\/www.hop-on-hop-off.net\/hu","nextItem":{"@type":"ListItem","@id":"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/#listItem","name":"Los Angeles: Hop-on\/Hop-off"}},{"@type":"ListItem","@id":"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/#listItem","position":2,"name":"Los Angeles: Hop-on\/Hop-off","previousItem":{"@type":"ListItem","@id":"https:\/\/www.hop-on-hop-off.net\/hu#listItem","name":"Startseite"}}]},{"@type":"Organization","@id":"https:\/\/www.hop-on-hop-off.net\/hu\/#organization","name":"Hop-on\/Hop-off","url":"https:\/\/www.hop-on-hop-off.net\/hu\/","logo":{"@type":"ImageObject","url":"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png","@id":"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/#organizationLogo","width":365,"height":70,"caption":"Hop-on\/Hop-off Bus"},"image":{"@id":"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/#webpage","url":"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/","name":"Los Angeles: Hop-on\/Hop-off - Routen & Fahrpl\u00e4ne 2026","description":"Hop-on\/Hop-off Los Angeles: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu 48 Stunden \u2713 30+ Haltestellen in Los Angeles. Jetzt informieren und Tickets kaufen.","inLanguage":"hu-HU","isPartOf":{"@id":"https:\/\/www.hop-on-hop-off.net\/hu\/#website"},"breadcrumb":{"@id":"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/#breadcrumblist"},"datePublished":"2023-11-16T14:04:51+00:00","dateModified":"2026-04-28T09:16:02+00:00"},{"@type":"WebSite","@id":"https:\/\/www.hop-on-hop-off.net\/hu\/#website","url":"https:\/\/www.hop-on-hop-off.net\/hu\/","name":"Hop-on\/Hop-off","inLanguage":"hu-HU","publisher":{"@id":"https:\/\/www.hop-on-hop-off.net\/hu\/#organization"}}]},"og:locale":"hu_HU","og:site_name":"Hop-on\/Hop-off.net -","og:type":"article","og:title":"Los Angeles: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne 2026","og:description":"Hop-on\/Hop-off Los Angeles: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu 48 Stunden \u2713 30+ Haltestellen in Los Angeles. Jetzt informieren und Tickets kaufen.","og:url":"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/","og:image":"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png","og:image:secure_url":"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png","article:published_time":"2023-11-16T14:04:51+00:00","article:modified_time":"2026-04-28T09:16:02+00:00","twitter:card":"summary_large_image","twitter:title":"Los Angeles: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne 2026","twitter:description":"Hop-on\/Hop-off Los Angeles: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu 48 Stunden \u2713 30+ Haltestellen in Los Angeles. Jetzt informieren und Tickets kaufen.","twitter:image":"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png"},"aioseo_meta_data":{"post_id":"1163","title":"Los Angeles: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne #current_year","description":"Hop-on\/Hop-off Los Angeles: Jegyek ak\u00e1r 48 \u00f3r\u00e1ra \u2713 30+ meg\u00e1ll\u00f3 Los Angelesben. Tudjon meg t\u00f6bbet \u00e9s v\u00e1s\u00e1roljon jegyet most.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-11-15 13:05:41","updated":"2026-04-28 09:16:22","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.hop-on-hop-off.net\/hu\" title=\"Startseite\">Startseite<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLos Angeles: Hop-on\/Hop-off\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Startseite","link":"https:\/\/www.hop-on-hop-off.net\/hu"},{"label":"Los Angeles: Hop-on\/Hop-off","link":"https:\/\/www.hop-on-hop-off.net\/hu\/los-angeles\/"}],"featured_image_src":null,"_links":{"self":[{"href":"https:\/\/www.hop-on-hop-off.net\/hu\/wp-json\/wp\/v2\/pages\/1163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hop-on-hop-off.net\/hu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hop-on-hop-off.net\/hu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hop-on-hop-off.net\/hu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hop-on-hop-off.net\/hu\/wp-json\/wp\/v2\/comments?post=1163"}],"version-history":[{"count":28,"href":"https:\/\/www.hop-on-hop-off.net\/hu\/wp-json\/wp\/v2\/pages\/1163\/revisions"}],"predecessor-version":[{"id":2921,"href":"https:\/\/www.hop-on-hop-off.net\/hu\/wp-json\/wp\/v2\/pages\/1163\/revisions\/2921"}],"wp:attachment":[{"href":"https:\/\/www.hop-on-hop-off.net\/hu\/wp-json\/wp\/v2\/media?parent=1163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}