{"id":1201,"date":"2023-11-17T13:48:17","date_gmt":"2023-11-17T13:48:17","guid":{"rendered":"https:\/\/www.hop-on-hop-off.net\/?page_id=1201"},"modified":"2026-05-12T07:47:21","modified_gmt":"2026-05-12T07:47:21","slug":"san-francisco","status":"publish","type":"page","link":"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/","title":{"rendered":"San Francisco: Salita e discesa"},"content":{"rendered":"<style>.kb-image1201_1d089b-19 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1201_1d089b-19 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"499\" src=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/san-francisco-skyline-sightseeing.jpg\" alt=\"Hop-on\/ Hop-off San Francisco: Skyline Sightseeing\" class=\"kb-img wp-image-1205\" srcset=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/san-francisco-skyline-sightseeing.jpg 800w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/san-francisco-skyline-sightseeing-300x187.jpg 300w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/san-francisco-skyline-sightseeing-768x479.jpg 768w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/san-francisco-skyline-sightseeing-18x12.jpg 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>\u00a9 Noah Boyer\/ Unsplash<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Hier finden Sie Informationen zu Stadtrundfahrten mit dem Hop-on\/Hop-off-Bus in San Francisco. Wir informieren Sie \u00fcber Haltestellen, Fahrpl\u00e4ne und Preise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Tickets k\u00f6nnen Sie direkt bei unseren Partnern buchen und auf Ihr Handy laden. F\u00fcr den Verkauf erhalten wir eine kleine Provision. Der Preis bleibt f\u00fcr Sie selbstverst\u00e4ndlich gleich.<\/p>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1201_0c469c-64{margin-bottom:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);}.kb-row-layout-id1201_0c469c-64 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1201_0c469c-64 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1201_0c469c-64 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1201_0c469c-64 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1201_0c469c-64 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1201_0c469c-64 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1201_0c469c-64 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1201_db80ff-9f > .kt-inside-inner-col,.kadence-column1201_db80ff-9f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1201_db80ff-9f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1201_db80ff-9f > .kt-inside-inner-col{flex-direction:column;}.kadence-column1201_db80ff-9f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1201_db80ff-9f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1201_db80ff-9f{position:relative;}@media all and (max-width: 1024px){.kadence-column1201_db80ff-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1201_db80ff-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1201_db80ff-9f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1201_be5283-38, .wp-block-kadence-advancedheading.kt-adv-heading1201_be5283-38[data-kb-block=\"kb-adv-heading1201_be5283-38\"]{text-align:center;font-style:normal;background-color:#b51310;border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}.wp-block-kadence-advancedheading.kt-adv-heading1201_be5283-38 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1201_be5283-38[data-kb-block=\"kb-adv-heading1201_be5283-38\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1201_be5283-38 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1201_be5283-38[data-kb-block=\"kb-adv-heading1201_be5283-38\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1201_be5283-38, .wp-block-kadence-advancedheading.kt-adv-heading1201_be5283-38[data-kb-block=\"kb-adv-heading1201_be5283-38\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1201_be5283-38, .wp-block-kadence-advancedheading.kt-adv-heading1201_be5283-38[data-kb-block=\"kb-adv-heading1201_be5283-38\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}<\/style>\n<h2 id=\"0-valencia-bus-tur%C3%ADstic\" class=\"kt-adv-heading1201_be5283-38 wp-block-kadence-advancedheading has-base-3-color has-text-color\" data-kb-block=\"kb-adv-heading1201_be5283-38\">Big Bus San Francisco<\/h2>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1201_969773-2d{margin-bottom:0px;}.kb-row-layout-id1201_969773-2d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1201_969773-2d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1201_969773-2d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1201_969773-2d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1201_969773-2d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1201_969773-2d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1201_969773-2d alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1201_cddaab-57 > .kt-inside-inner-col,.kadence-column1201_cddaab-57 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1201_cddaab-57 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1201_cddaab-57 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1201_cddaab-57 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1201_cddaab-57 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1201_cddaab-57{position:relative;}@media all and (max-width: 1024px){.kadence-column1201_cddaab-57 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1201_cddaab-57 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1201_cddaab-57\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1201_f7205d-94 > .kt-inside-inner-col,.kadence-column1201_f7205d-94 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1201_f7205d-94 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1201_f7205d-94 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1201_f7205d-94 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1201_f7205d-94 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1201_f7205d-94{position:relative;}.kadence-column1201_f7205d-94, .kt-inside-inner-col > .kadence-column1201_f7205d-94:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column1201_f7205d-94 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1201_f7205d-94 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1201_f7205d-94\"><div class=\"kt-inside-inner-col\">\n<div data-tiqets-widget=\"availability\" data-layout=\"full\" data-orientation=\"horizontal\" data-product-id=\"1035514\" data-partner=\"hopon\"><\/div>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1201_6a6f44-06, .wp-block-kadence-advancedheading.kt-adv-heading1201_6a6f44-06[data-kb-block=\"kb-adv-heading1201_6a6f44-06\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1201_6a6f44-06 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1201_6a6f44-06[data-kb-block=\"kb-adv-heading1201_6a6f44-06\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1201_6a6f44-06 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1201_6a6f44-06[data-kb-block=\"kb-adv-heading1201_6a6f44-06\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p id=\"1-valencia-bus-turistic-bietet-seit-1999-stadtrundfahrten-an-die-roten-hop-onhop-off-busse-bedienen-haltestellen-die-%C3%BCber-ganz-valencia-verteilt-sind-an-bord-gibt-es-einen-audioguide-in-10-sprachen\" class=\"kt-adv-heading1201_6a6f44-06 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1201_6a6f44-06\">Big Bus ist einer der gr\u00f6\u00dften Anbieter von Hop-on-Hop-off-Touren und bietet in San Francisco auch Stadtrundfahrten am Abend an. <\/p>\n\n\n<style>.kadence-column1201_c03ba1-d2 > .kt-inside-inner-col,.kadence-column1201_c03ba1-d2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1201_c03ba1-d2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1201_c03ba1-d2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1201_c03ba1-d2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1201_c03ba1-d2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1201_c03ba1-d2{position:relative;}.kadence-column1201_c03ba1-d2, .kt-inside-inner-col > .kadence-column1201_c03ba1-d2:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column1201_c03ba1-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1201_c03ba1-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1201_c03ba1-d2\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id1201_a93f7d-76 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:5px;}.kt-accordion-id1201_a93f7d-76 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id1201_a93f7d-76 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:var(--contrast);padding-top:10px;padding-right:14px;padding-bottom:10px;padding-left:14px;}.kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--contrast);}.kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--contrast);}.kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id1201_a93f7d-76 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1201_a93f7d-76 .kt-blocks-accordion-header:focus-visible{color:#444444;background:var(--base-2);border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--base-2);}.kt-accordion-id1201_a93f7d-76 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1201_a93f7d-76 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#e51b22;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1201_a93f7d-76:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#e51b22;}@media all and (max-width: 1024px){.kt-accordion-id1201_a93f7d-76 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id1201_a93f7d-76 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id1201_a93f7d-76 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1201_a93f7d-76 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id1201_a93f7d-76 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1201_a93f7d-76 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id1201_a93f7d-76 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id1201_a93f7d-76 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:5px;}.kt-accordion-id1201_a93f7d-76 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id1201_a93f7d-76 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id1201_a93f7d-76 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1201_a93f7d-76 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id1201_a93f7d-76 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1201_a93f7d-76 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id1201_a93f7d-76 kt-accordion-has-4-panes kt-active-pane-3 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane1201_6fe516-a6\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Routen &amp; Haltestellen<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_a75bc5-07:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_a75bc5-07 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_a75bc5-07 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_a75bc5-07 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_a75bc5-07 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1201_a75bc5-07 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1201_a75bc5-07 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1201_5c5e17-58 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_5c5e17-58\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">1 Route \u2013&nbsp;15 Haltestellen<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_0d83cb-d6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_0d83cb-d6\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Start-Haltestelle: Big Bus Visitor Center<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_4dbda4-f8 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_4dbda4-f8\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Optional: Stadtrundfahrt bei Nacht<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_da58b3-35 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_da58b3-35\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/www.bigbustours.com\/en\/san-francisco\/san-francisco-bus-tours?utm_source=Commission_Junction&amp;utm_medium=Affiliate_Marketing&amp;utm_campaign=Patrick+K%C3%BChne_101037000&amp;cjevent=898851ae095211f080fd02b70a18b8fb\" target=\"_blank\" rel=\"noopener\" title=\"\">Karte mit Route &amp; Haltestellen<\/a><\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane1201_14d172-04\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Fahrplan Rote Linie<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_3258b8-96:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_3258b8-96 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_3258b8-96 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_3258b8-96 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_3258b8-96 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1201_3258b8-96 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1201_3258b8-96 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1201_ace1e5-dd .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_ace1e5-dd\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Erste Abfahrt: 10:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_7ea303-e7 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_7ea303-e7\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Letzte Abfahrt: 17:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_648692-74 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_648692-74\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Frequenz: alle 15 Minuten <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_97f105-42 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_97f105-42\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Dauer der Rundfahrt: 2,5 Stunden<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane1201_69cdd3-33\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Stadtrundfahrt am Abend<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_c5d9af-7b:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_c5d9af-7b ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_c5d9af-7b ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_c5d9af-7b .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_c5d9af-7b ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1201_c5d9af-7b ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1201_c5d9af-7b kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1201_135265-f7 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_135265-f7\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">T\u00e4glich 18:30 <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_1096b8-a0 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_1096b8-a0\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Start-Haltestelle: 99 Jefferson Street<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_59d329-3b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_59d329-3b\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Dauer der Rundfahrt: 1 Stunde<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane1201_9da04e-9e\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Kontakt: Big Bus San Francisco<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1201_653497-28, .wp-block-kadence-advancedheading.kt-adv-heading1201_653497-28[data-kb-block=\"kb-adv-heading1201_653497-28\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1201_653497-28 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1201_653497-28[data-kb-block=\"kb-adv-heading1201_653497-28\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1201_653497-28 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1201_653497-28[data-kb-block=\"kb-adv-heading1201_653497-28\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1201_653497-28 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1201_653497-28\">Sollten Sie Fragen an das Unternehmen haben oder sich beschweren wollen, k\u00f6nnen Sie Big Bus San Francisco \u00fcber folgendes Kontaktformular erreichen:<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_155478-da:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_155478-da ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_155478-da ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_155478-da .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_155478-da ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1201_155478-da ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1201_155478-da kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1201_0fd80f-5e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_0fd80f-5e\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mail kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M4 4h16c1.1 0 2 .9 2 2v12c0 1.1-.9 2-2 2H4c-1.1 0-2-.9-2-2V6c0-1.1.9-2 2-2z\"\/><polyline points=\"22,6 12,13 2,6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/www.bigbustours.com\/en\/san-francisco\/contact-us\" target=\"_blank\" rel=\"noopener\" title=\"\">Kontaktformular<\/a><\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1201_544390-04, .wp-block-kadence-advancedheading.kt-adv-heading1201_544390-04[data-kb-block=\"kb-adv-heading1201_544390-04\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1201_544390-04 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1201_544390-04[data-kb-block=\"kb-adv-heading1201_544390-04\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1201_544390-04 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1201_544390-04[data-kb-block=\"kb-adv-heading1201_544390-04\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1201_544390-04 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1201_544390-04\">Wenn Sie Fragen zur Ticketbuchung haben, wenden Sie sich bitte an den Kundenservice von Tiqets.com oder GetYourGuide (je nachdem, wo Sie Ihr Ticket gebucht haben).<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">An Bord gibt es einen mehrsprachigen Audioguide. Mit der kostenlosen Big Bus App k\u00f6nnen Sie die Busse live verfolgen.<\/p>\n\n\n<p><strong>Ticketg\u00fcltigkeit:<\/strong> 1-2 Tage<br \/>\n<strong>Bewertung:<\/strong> 4,7 (29 Reviews)<br \/>\n<strong>Preis:<\/strong> ab $59.40<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns1201_611e4a-85{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns1201_611e4a-85 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1201_611e4a-85 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1201_611e4a-85 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1201_611e4a-85 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1201_611e4a-85 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1201_611e4a-85 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1201_611e4a-85 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1201_611e4a-85 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1201_611e4a-85\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1201_c28db8-d9.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1201_c28db8-d9.kb-button{color:var(--base-3);background:#e51b22;box-shadow:2px 2px 2px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn1201_c28db8-d9.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1201_c28db8-d9.kb-button:focus{color:var(--base-3);background:#b51310;}<\/style><a class=\"kb-button kt-button button kb-btn1201_c28db8-d9 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/www.tiqets.com\/de\/checkout\/tickets-fur-san-francisco-hop-on-hop-off-bus-p1035514\/booking_details\/?partner=hopon\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_externalLink kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Tickets kaufen<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1201_583a00-1a, .wp-block-kadence-advancedheading.kt-adv-heading1201_583a00-1a[data-kb-block=\"kb-adv-heading1201_583a00-1a\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1201_583a00-1a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1201_583a00-1a[data-kb-block=\"kb-adv-heading1201_583a00-1a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1201_583a00-1a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1201_583a00-1a[data-kb-block=\"kb-adv-heading1201_583a00-1a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1201_583a00-1a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1201_583a00-1a\">Wenn Sie Ihr Ticket online kaufen, erhalten Sie anschlie\u00dfend einen Voucher, den Sie auf Ihrem Handy speichern k\u00f6nnen. Zeigen Sie diesen Voucher dem Buspersonal bei der ersten Fahrt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tipp:<\/strong> Mit einem Kombiticket k\u00f6nnen Sie den Bus nutzen und eine Attraktion besuchen. So sparen Sie etwas Geld.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.bigbustours.com\/en\/san-francisco\/san-francisco-bus-tours?utm_source=Commission_Junction&amp;utm_medium=Affiliate_Marketing&amp;utm_campaign=Patrick+K%C3%BChne_101037000&amp;cjevent=a2e40ce2095411f080f202b00a18b8fa\" target=\"_blank\" rel=\"noopener nofollow sponsored\" title=\"\">Hop-on\/Hop-off-Bus + Alcatraz<\/a><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1201_a14ab2-1a{margin-bottom:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);}.kb-row-layout-id1201_a14ab2-1a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1201_a14ab2-1a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1201_a14ab2-1a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1201_a14ab2-1a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1201_a14ab2-1a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1201_a14ab2-1a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1201_a14ab2-1a alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1201_8cf628-11 > .kt-inside-inner-col,.kadence-column1201_8cf628-11 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1201_8cf628-11 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1201_8cf628-11 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1201_8cf628-11 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1201_8cf628-11 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1201_8cf628-11{position:relative;}@media all and (max-width: 1024px){.kadence-column1201_8cf628-11 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1201_8cf628-11 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1201_8cf628-11\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1201_e40c35-18, .wp-block-kadence-advancedheading.kt-adv-heading1201_e40c35-18[data-kb-block=\"kb-adv-heading1201_e40c35-18\"]{text-align:center;font-style:normal;background-color:#b51310;border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}.wp-block-kadence-advancedheading.kt-adv-heading1201_e40c35-18 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1201_e40c35-18[data-kb-block=\"kb-adv-heading1201_e40c35-18\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1201_e40c35-18 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1201_e40c35-18[data-kb-block=\"kb-adv-heading1201_e40c35-18\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1201_e40c35-18, .wp-block-kadence-advancedheading.kt-adv-heading1201_e40c35-18[data-kb-block=\"kb-adv-heading1201_e40c35-18\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1201_e40c35-18, .wp-block-kadence-advancedheading.kt-adv-heading1201_e40c35-18[data-kb-block=\"kb-adv-heading1201_e40c35-18\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}<\/style>\n<h2 id=\"0-valencia-bus-tur%C3%ADstic\" class=\"kt-adv-heading1201_e40c35-18 wp-block-kadence-advancedheading has-base-3-color has-text-color\" data-kb-block=\"kb-adv-heading1201_e40c35-18\">Skyline Sightseeing<\/h2>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1201_283c97-7c{margin-bottom:0px;}.kb-row-layout-id1201_283c97-7c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1201_283c97-7c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1201_283c97-7c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}.kb-row-layout-id1201_283c97-7c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1201_283c97-7c > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1201_283c97-7c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1201_283c97-7c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1201_f15a8d-74 > .kt-inside-inner-col,.kadence-column1201_f15a8d-74 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1201_f15a8d-74 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1201_f15a8d-74 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1201_f15a8d-74 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1201_f15a8d-74 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1201_f15a8d-74{position:relative;}@media all and (max-width: 1024px){.kadence-column1201_f15a8d-74 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1201_f15a8d-74 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1201_f15a8d-74\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1201_e9c7ff-02 > .kt-inside-inner-col,.kadence-column1201_e9c7ff-02 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1201_e9c7ff-02 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1201_e9c7ff-02 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1201_e9c7ff-02 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1201_e9c7ff-02 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1201_e9c7ff-02{position:relative;}.kadence-column1201_e9c7ff-02, .kt-inside-inner-col > .kadence-column1201_e9c7ff-02:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column1201_e9c7ff-02 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1201_e9c7ff-02 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1201_e9c7ff-02 kvs-lg-false kvs-md-false\"><div class=\"kt-inside-inner-col\"><style>.kb-image1201_fb2095-74 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1201_fb2095-74 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"499\" src=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/san-francisco-skyline-sightseeing.jpg\" alt=\"Hop-on\/ Hop-off San Francisco: Skyline Sightseeing\" class=\"kb-img wp-image-1205\" srcset=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/san-francisco-skyline-sightseeing.jpg 800w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/san-francisco-skyline-sightseeing-300x187.jpg 300w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/san-francisco-skyline-sightseeing-768x479.jpg 768w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/11\/san-francisco-skyline-sightseeing-18x12.jpg 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>\u00a9 Noah Boyer\/ Unsplash<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1201_5b0100-ae, .wp-block-kadence-advancedheading.kt-adv-heading1201_5b0100-ae[data-kb-block=\"kb-adv-heading1201_5b0100-ae\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1201_5b0100-ae mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1201_5b0100-ae[data-kb-block=\"kb-adv-heading1201_5b0100-ae\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1201_5b0100-ae img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1201_5b0100-ae[data-kb-block=\"kb-adv-heading1201_5b0100-ae\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p id=\"1-valencia-bus-turistic-bietet-seit-1999-stadtrundfahrten-an-die-roten-hop-onhop-off-busse-bedienen-haltestellen-die-%C3%BCber-ganz-valencia-verteilt-sind-an-bord-gibt-es-einen-audioguide-in-10-sprachen\" class=\"kt-adv-heading1201_5b0100-ae wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1201_5b0100-ae\">Skyline Sightseeing ist ein in San Francisco ans\u00e4ssiges Unternehmen, das in der Stadt eine Hop-on-Hop-off-Tour sowie eine Nacht-Tour anbietet. <\/p>\n\n\n<style>.kadence-column1201_84267b-96 > .kt-inside-inner-col,.kadence-column1201_84267b-96 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1201_84267b-96 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1201_84267b-96 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1201_84267b-96 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1201_84267b-96 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1201_84267b-96{position:relative;}.kadence-column1201_84267b-96, .kt-inside-inner-col > .kadence-column1201_84267b-96:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column1201_84267b-96 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1201_84267b-96 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1201_84267b-96\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id1201_783cb4-eb .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:5px;}.kt-accordion-id1201_783cb4-eb .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id1201_783cb4-eb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:var(--contrast);padding-top:10px;padding-right:14px;padding-bottom:10px;padding-left:14px;}.kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--contrast);}.kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--contrast);}.kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id1201_783cb4-eb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1201_783cb4-eb .kt-blocks-accordion-header:focus-visible{color:#444444;background:var(--base-2);border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--base-2);}.kt-accordion-id1201_783cb4-eb .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1201_783cb4-eb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#e51b22;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1201_783cb4-eb:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#e51b22;}@media all and (max-width: 1024px){.kt-accordion-id1201_783cb4-eb .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id1201_783cb4-eb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id1201_783cb4-eb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1201_783cb4-eb .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id1201_783cb4-eb .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1201_783cb4-eb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id1201_783cb4-eb .kt-accordion-inner-wrap{display:block;}.kt-accordion-id1201_783cb4-eb .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:5px;}.kt-accordion-id1201_783cb4-eb .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id1201_783cb4-eb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id1201_783cb4-eb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1201_783cb4-eb .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id1201_783cb4-eb .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1201_783cb4-eb > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id1201_783cb4-eb kt-accordion-has-4-panes kt-active-pane-3 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane1201_34ddef-13\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Routen &amp; Haltestellen<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_9c204f-71:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_9c204f-71 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_9c204f-71 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_9c204f-71 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_9c204f-71 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1201_9c204f-71 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1201_9c204f-71 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1201_98296a-ab .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_98296a-ab\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">1 Route \u2013&nbsp;15+ Haltestellen<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_018632-04 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_018632-04\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Start-Haltestelle: 99 Jefferson Street\/ Fisherman\u2019s Wharf<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_2b330f-89 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_2b330f-89\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Optional: Stadtrundfahrt bei Nacht<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_97c610-3b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_97c610-3b\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/res.cloudinary.com\/hynomj8e0\/image\/upload\/wnwgindnx7sww5xek4xd.jpg\" target=\"_blank\" rel=\"noopener\" title=\"\">Karte mit Route &amp; Haltestellen<\/a><\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane1201_272382-56\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Fahrplan <\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_043bd1-ec:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_043bd1-ec ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_043bd1-ec ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_043bd1-ec .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_043bd1-ec ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1201_043bd1-ec ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1201_043bd1-ec kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1201_1fc6e5-ee .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_1fc6e5-ee\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Erste Abfahrt: 10:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_1287f9-8b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_1287f9-8b\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Letzte Abfahrt: 17:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_3def35-f1 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_3def35-f1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Frequenz: alle 30-60 Minuten <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_163c1b-39 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_163c1b-39\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Dauer der Rundfahrt: 2 Stunden<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane1201_489df3-76\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Stadtrundfahrt am Abend<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_2a9b0e-b0:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_2a9b0e-b0 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_2a9b0e-b0 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_2a9b0e-b0 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_2a9b0e-b0 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1201_2a9b0e-b0 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1201_2a9b0e-b0 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1201_80f670-0c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_80f670-0c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">T\u00e4glich 18:30 <\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_5be66e-cf .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_5be66e-cf\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Start-Haltestelle: 99 Jefferson Street<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_4bb12e-ef .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_4bb12e-ef\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Dauer der Rundfahrt: 1 Stunde<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane1201_491f3b-6e\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Kontakt: Skyline Sightseeing<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1201_a3e854-2a, .wp-block-kadence-advancedheading.kt-adv-heading1201_a3e854-2a[data-kb-block=\"kb-adv-heading1201_a3e854-2a\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1201_a3e854-2a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1201_a3e854-2a[data-kb-block=\"kb-adv-heading1201_a3e854-2a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1201_a3e854-2a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1201_a3e854-2a[data-kb-block=\"kb-adv-heading1201_a3e854-2a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1201_a3e854-2a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1201_a3e854-2a\">Sollten Sie Fragen an das Unternehmen haben oder sich beschweren wollen, k\u00f6nnen Sie Skyline Sightseeing per E-Mail kontaktieren:<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_0f9aa6-a2:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_0f9aa6-a2 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_0f9aa6-a2 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_0f9aa6-a2 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_0f9aa6-a2 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1201_0f9aa6-a2 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1201_0f9aa6-a2 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1201_add5ec-bb .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_add5ec-bb\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mail kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M4 4h16c1.1 0 2 .9 2 2v12c0 1.1-.9 2-2 2H4c-1.1 0-2-.9-2-2V6c0-1.1.9-2 2-2z\"\/><polyline points=\"22,6 12,13 2,6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">info@sightseeingworld.com<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1201_2b4354-39, .wp-block-kadence-advancedheading.kt-adv-heading1201_2b4354-39[data-kb-block=\"kb-adv-heading1201_2b4354-39\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1201_2b4354-39 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1201_2b4354-39[data-kb-block=\"kb-adv-heading1201_2b4354-39\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1201_2b4354-39 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1201_2b4354-39[data-kb-block=\"kb-adv-heading1201_2b4354-39\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1201_2b4354-39 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1201_2b4354-39\">Wenn Sie Fragen zur Ticketbuchung haben, wenden Sie sich bitte an den Kundenservice von Tiqets.com oder GetYourGuide (je nachdem, wo Sie Ihr Ticket gebucht haben).<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">An Bord gibt es einen mehrsprachigen Audioguide. <\/p>\n\n\n<p><strong>Ticketg\u00fcltigkeit:<\/strong> 2 Tage<br \/>\n<strong>Bewertung:<\/strong> 4,4 (325 Reviews)<br \/>\n<strong>Preis:<\/strong> $159.99<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns1201_20e0ac-18{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns1201_20e0ac-18 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1201_20e0ac-18 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1201_20e0ac-18 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1201_20e0ac-18 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1201_20e0ac-18 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1201_20e0ac-18 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1201_20e0ac-18 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1201_20e0ac-18 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1201_20e0ac-18\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1201_71d497-23.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1201_71d497-23.kb-button{color:var(--base-3);background:#e51b22;box-shadow:2px 2px 2px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn1201_71d497-23.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1201_71d497-23.kb-button:focus{color:var(--base-3);background:#b51310;}<\/style><a class=\"kb-button kt-button button kb-btn1201_71d497-23 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/www.getyourguide.de\/san-francisco-l61\/san-francisco-hop-on-hop-off-48-stunden-karte-mit-4-routen-t11316\/?partner_id=B0910&#038;cmp=hopon&#038;mkt_cmp=true\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_externalLink kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Tickets kaufen<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1201_1b6120-f6 > .kt-inside-inner-col,.kadence-column1201_1b6120-f6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1201_1b6120-f6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1201_1b6120-f6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1201_1b6120-f6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1201_1b6120-f6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1201_1b6120-f6{position:relative;}@media all and (max-width: 1024px){.kadence-column1201_1b6120-f6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1201_1b6120-f6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1201_1b6120-f6 kvs-sm-false\"><div class=\"kt-inside-inner-col\"><style>.kb-image1201_8797e0-42 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1201_8797e0-42 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"334\" height=\"500\" src=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2025\/03\/tourist-hop-on-hop-off-bus.jpg\" alt=\"Hop-on\/Hop-off-Tour: Touristenpaar bei einer Stadtrundfahrt\" class=\"kb-img wp-image-2570\" srcset=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2025\/03\/tourist-hop-on-hop-off-bus.jpg 334w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2025\/03\/tourist-hop-on-hop-off-bus-200x300.jpg 200w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2025\/03\/tourist-hop-on-hop-off-bus-8x12.jpg 8w\" sizes=\"auto, (max-width: 334px) 100vw, 334px\" \/><figcaption>\u00a9 Daxiao Productions\/ Shutterstock.com<\/figcaption><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1201_85f69e-7e, .wp-block-kadence-advancedheading.kt-adv-heading1201_85f69e-7e[data-kb-block=\"kb-adv-heading1201_85f69e-7e\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1201_85f69e-7e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1201_85f69e-7e[data-kb-block=\"kb-adv-heading1201_85f69e-7e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1201_85f69e-7e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1201_85f69e-7e[data-kb-block=\"kb-adv-heading1201_85f69e-7e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1201_85f69e-7e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1201_85f69e-7e\">Wenn Sie Ihr Ticket online kaufen, erhalten Sie anschlie\u00dfend einen Voucher, den Sie auf Ihrem Handy speichern k\u00f6nnen. Diesen m\u00fcssen Sie vor Fahrtantritt am Pier 41 gegen ein Papierticket umtauschen.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1201_3c5486-37{margin-bottom:0px;margin-bottom:var(--global-kb-spacing-md, 2rem);}.kb-row-layout-id1201_3c5486-37 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1201_3c5486-37 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1201_3c5486-37 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1201_3c5486-37 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1201_3c5486-37 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1201_3c5486-37 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1201_3c5486-37 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1201_e56450-e5 > .kt-inside-inner-col,.kadence-column1201_e56450-e5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1201_e56450-e5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1201_e56450-e5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1201_e56450-e5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1201_e56450-e5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1201_e56450-e5{position:relative;}@media all and (max-width: 1024px){.kadence-column1201_e56450-e5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1201_e56450-e5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1201_e56450-e5\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1201_1cc33c-82, .wp-block-kadence-advancedheading.kt-adv-heading1201_1cc33c-82[data-kb-block=\"kb-adv-heading1201_1cc33c-82\"]{font-style:normal;background-color:#b51310;border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}.wp-block-kadence-advancedheading.kt-adv-heading1201_1cc33c-82 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1201_1cc33c-82[data-kb-block=\"kb-adv-heading1201_1cc33c-82\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1201_1cc33c-82 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1201_1cc33c-82[data-kb-block=\"kb-adv-heading1201_1cc33c-82\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1201_1cc33c-82, .wp-block-kadence-advancedheading.kt-adv-heading1201_1cc33c-82[data-kb-block=\"kb-adv-heading1201_1cc33c-82\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1201_1cc33c-82, .wp-block-kadence-advancedheading.kt-adv-heading1201_1cc33c-82[data-kb-block=\"kb-adv-heading1201_1cc33c-82\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}<\/style>\n<h2 id=\"11-hop-onhop-off-sehensw%C3%BCrdigkeiten\" class=\"kt-adv-heading1201_1cc33c-82 wp-block-kadence-advancedheading has-base-3-color has-text-color\" data-kb-block=\"kb-adv-heading1201_1cc33c-82\">Hop-on\/Hop-off: Sehensw\u00fcrdigkeiten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die kalifornische Stadt hat neben der Golden Gate Bridge noch zahlreiche weitere Sehensw\u00fcrdigkeiten zu bieten. Die meisten davon k\u00f6nnen Sie bei einer Stadtrundfahrt mit dem Hop-on\/Hop-off-Bus erreichen:<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_83491b-50:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_83491b-50 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_83491b-50 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_83491b-50 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_83491b-50 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1201_83491b-50 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}@media all and (min-width: 1025px){.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_83491b-50:not(.kt-svg-icon-list-columns-1) ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap:not(:last-child){margin:0px;}}@media all and (min-width: 768px) and (max-width: 1024px){.wp-block-kadence-iconlist.kt-svg-icon-list-items1201_83491b-50:not(.kt-tablet-svg-icon-list-columns-1) ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap:not(:last-child){margin:0px;}}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1201_83491b-50 kt-svg-icon-list-columns-2 alignnone kt-mobile-svg-icon-list-columns-1\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1201_ff2b53-46 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_ff2b53-46\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Golden Gate Bridge<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_1b380c-78 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_1b380c-78\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Lombard Street<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_72b3a2-72 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_72b3a2-72\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Alcatraz Island<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_a85b57-ed .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_a85b57-ed\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Painted Ladies<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_ae8383-09 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_ae8383-09\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Fisherman&#8217;s Wharf<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_7b4a19-a6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_7b4a19-a6\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Museum of Modern Art<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_864a4d-f2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_864a4d-f2\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Pier 39<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_01f74c-a6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_01f74c-a6\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Golden Gate Park<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_e13c51-9e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_e13c51-9e\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Chinatown<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1201_d4af2d-50 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1201_d4af2d-50\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Coit Tower<\/span><\/li>\n<\/ul><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Steigen Sie einfach an der n\u00e4chstgelegenen Haltestelle aus, besichtigen Sie eine Sehensw\u00fcrdigkeit und fahren Sie dann weiter. Die Busse von Big Bus fahren alle 15 Minuten, so dass Sie nicht lange warten m\u00fcssen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch wenn es nicht f\u00fcr jede Sehensw\u00fcrdigkeit eine eigene Haltestelle gibt, k\u00f6nnen Sie alle Attraktionen mit dem Bus erreichen. Manchmal ist noch ein kurzer Fu\u00dfweg n\u00f6tig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lediglich die Gef\u00e4ngnisinsel Alcatraz ist nicht mit dem Hop-on-Hop-off-Bus erreichbar. Hier empfiehlt sich der Kauf eines Kombitickets. Dieses erm\u00f6glicht Ihnen die Fahrt mit dem Hop-on-Hop-off-Bus und beinhaltet ein Ticket f\u00fcr die F\u00e4hre und den Eintritt nach Alcatraz.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns1201_5f90dd-05{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns1201_5f90dd-05 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1201_5f90dd-05 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1201_5f90dd-05 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1201_5f90dd-05 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1201_5f90dd-05 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1201_5f90dd-05 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1201_5f90dd-05 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1201_5f90dd-05 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1201_5f90dd-05\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1201_49326b-20.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1201_49326b-20.kb-button{color:var(--base-3);background:#e51b22;box-shadow:2px 2px 2px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn1201_49326b-20.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1201_49326b-20.kb-button:focus{color:var(--base-3);background:#b51310;}<\/style><a class=\"kb-button kt-button button kb-btn1201_49326b-20 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/www.tiqets.com\/de\/checkout\/tickets-fur-san-francisco-hop-on-hop-off-bus-p1035514\/booking_details\/?partner=hopon\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_externalLink kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Tickets kaufen<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1201_5b459e-31{margin-bottom:0px;}.kb-row-layout-id1201_5b459e-31 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1201_5b459e-31 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1201_5b459e-31 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1201_5b459e-31 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1201_5b459e-31 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1201_5b459e-31 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1201_5b459e-31 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1201_1629df-bb > .kt-inside-inner-col,.kadence-column1201_1629df-bb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1201_1629df-bb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1201_1629df-bb > .kt-inside-inner-col{flex-direction:column;}.kadence-column1201_1629df-bb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1201_1629df-bb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1201_1629df-bb{position:relative;}@media all and (max-width: 1024px){.kadence-column1201_1629df-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1201_1629df-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1201_1629df-bb\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1201_babf0a-6d, .wp-block-kadence-advancedheading.kt-adv-heading1201_babf0a-6d[data-kb-block=\"kb-adv-heading1201_babf0a-6d\"]{font-style:normal;background-color:#b51310;border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}.wp-block-kadence-advancedheading.kt-adv-heading1201_babf0a-6d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1201_babf0a-6d[data-kb-block=\"kb-adv-heading1201_babf0a-6d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1201_babf0a-6d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1201_babf0a-6d[data-kb-block=\"kb-adv-heading1201_babf0a-6d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1201_babf0a-6d, .wp-block-kadence-advancedheading.kt-adv-heading1201_babf0a-6d[data-kb-block=\"kb-adv-heading1201_babf0a-6d\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1201_babf0a-6d, .wp-block-kadence-advancedheading.kt-adv-heading1201_babf0a-6d[data-kb-block=\"kb-adv-heading1201_babf0a-6d\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}<\/style>\n<h2 id=\"12-lohnt-sich-eine-valencia-stadtrundfahrt\" class=\"kt-adv-heading1201_babf0a-6d wp-block-kadence-advancedheading has-base-3-color has-text-color\" data-kb-block=\"kb-adv-heading1201_babf0a-6d\">Lohnt sich eine San Francisco-Stadtrundfahrt?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Inmitten der sanft geschwungenen H\u00fcgel und der schillernden Skyline von San Francisco bietet eine Hop-on-Hop-off-Tour mit den markanten roten Doppeldeckerbussen eine bequeme und flexible M\u00f6glichkeit, die Vielfalt und Sch\u00f6nheit der Stadt an der amerikanischen Westk\u00fcste zu erkunden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Sehensw\u00fcrdigkeiten der Stadt liegen zum Teil weit voneinander entfernt. Mit dem Hop-on-Hop-off-Bus k\u00f6nnen Sie fast alle Sehensw\u00fcrdigkeiten bequem erreichen, ohne lange Fu\u00dfwege in Kauf nehmen oder sich Gedanken \u00fcber ein geeignetes Transportmittel machen zu m\u00fcssen. Sie k\u00f6nnen an jeder Haltestelle aus- und wieder einsteigen und so die Stadt in Ihrem eigenen Tempo erkunden. Die Routen sind sorgf\u00e4ltig geplant und an die Bed\u00fcrfnisse der Reisenden angepasst. So verpassen Sie garantiert keine wichtige Sehensw\u00fcrdigkeit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die charakteristischen roten Doppeldeckerbusse, die f\u00fcr den Hop-on-Hop-off-Service in San Francisco eingesetzt werden, bieten nicht nur eine bequeme Fortbewegung, sondern auch einen erh\u00f6hten Ausblick auf die Stadt. Von der oberen Etage aus haben die Besucher einen atemberaubenden Blick auf Wahrzeichen wie die Golden Gate Bridge, Alcatraz und die Skyline von San Francisco.<\/p>\n\n\n<style>.kb-image1201_1b0d33-92 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1201_1b0d33-92 size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off-8.jpg\" alt=\"Hop-on\/Hop-off-Bus\" class=\"kb-img wp-image-274\" srcset=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off-8.jpg 800w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off-8-300x188.jpg 300w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off-8-768x480.jpg 768w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off-8-18x12.jpg 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>\u00a9 AboutLife \/ Shutterstock.com<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ein weiterer Vorteil ist das informative Audio-Kommentarsystem an Bord der Busse. Sie erhalten w\u00e4hrend der Stadtrundfahrt interessante Hintergrundinformationen zu den Sehensw\u00fcrdigkeiten. Dies tr\u00e4gt dazu bei, das kulturelle und historische Verst\u00e4ndnis der Besucher zu vertiefen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Hop-on-Hop-off-Service erm\u00f6glicht es, die einzigartige Atmosph\u00e4re dieser faszinierenden Metropole auf eigene Faust zu entdecken. Die Busse sind die ideale L\u00f6sung f\u00fcr Besucher, die in kurzer Zeit m\u00f6glichst viel von San Francisco sehen m\u00f6chten.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns1201_4a56fd-ce{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns1201_4a56fd-ce .kt-button{font-weight:normal;font-style:normal;}.kt-btns1201_4a56fd-ce .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1201_4a56fd-ce .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1201_4a56fd-ce .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1201_4a56fd-ce .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1201_4a56fd-ce .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1201_4a56fd-ce .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1201_4a56fd-ce .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1201_4a56fd-ce\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1201_27b384-e7.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1201_27b384-e7.kb-button{color:var(--base-3);background:#e51b22;box-shadow:2px 2px 2px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn1201_27b384-e7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1201_27b384-e7.kb-button:focus{color:var(--base-3);background:#b51310;}<\/style><a class=\"kb-button kt-button button kb-btn1201_27b384-e7 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/www.tiqets.com\/de\/checkout\/tickets-fur-san-francisco-hop-on-hop-off-bus-p1035514\/booking_details\/?partner=hopon\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_externalLink kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Tickets kaufen<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Qui troverete informazioni sui giri turistici in autobus hop-on hop-off a San Francisco. Vi informiamo su fermate, orari e prezzi. Potete prenotare i biglietti direttamente presso i nostri partner e scaricarli sul vostro cellulare. Riceviamo una piccola commissione per la vendita. Naturalmente, il prezzo rimane invariato per voi. Big Bus San Francisco Big Bus ... <a title=\"San Francisco: Salita e discesa\" class=\"read-more\" href=\"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/\" aria-label=\"Per saperne di pi\u00f9 su San Francisco: Hop-on\/Hop-off\">Leggi tutto<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1201","page","type-page","status-publish"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hop-on\/Hop-off San Francisco: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu 48 Stunden \u2713 15+ Haltestellen in San Francisco. Jetzt informieren und Tickets kaufen.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Hop-on\/Hop-off.net -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"San Francisco: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne 2026\" \/>\n\t\t<meta property=\"og:description\" content=\"Hop-on\/Hop-off San Francisco: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu 48 Stunden \u2713 15+ Haltestellen in San Francisco. Jetzt informieren und Tickets kaufen.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-11-17T13:48:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-12T07:47:21+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"San Francisco: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne 2026\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hop-on\/Hop-off San Francisco: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu 48 Stunden \u2713 15+ Haltestellen in San Francisco. Jetzt informieren und Tickets kaufen.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\\\/san-francisco\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it#listItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\\\/san-francisco\\\/#listItem\",\"name\":\"San Francisco: Hop-on\\\/Hop-off\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\\\/san-francisco\\\/#listItem\",\"position\":2,\"name\":\"San Francisco: Hop-on\\\/Hop-off\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it#listItem\",\"name\":\"Startseite\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\\\/#organization\",\"name\":\"Hop-on\\\/Hop-off\",\"url\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/hop-on-hop-off.png\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\\\/san-francisco\\\/#organizationLogo\",\"width\":365,\"height\":70,\"caption\":\"Hop-on\\\/Hop-off Bus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\\\/san-francisco\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\\\/san-francisco\\\/#webpage\",\"url\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\\\/san-francisco\\\/\",\"name\":\"San Francisco: Hop-on\\\/Hop-off - Routen & Fahrpl\\u00e4ne 2026\",\"description\":\"Hop-on\\\/Hop-off San Francisco: \\u2713 Stadtrundfahrt im Bus \\u2713 Tickets f\\u00fcr bis zu 48 Stunden \\u2713 15+ Haltestellen in San Francisco. Jetzt informieren und Tickets kaufen.\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\\\/san-francisco\\\/#breadcrumblist\"},\"datePublished\":\"2023-11-17T13:48:17+00:00\",\"dateModified\":\"2026-05-12T07:47:21+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\\\/\",\"name\":\"Hop-on\\\/Hop-off\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"San Francisco: Hop-on\/Hop-off - Percorsi e orari 2026","description":"Hop-on\/Hop-off San Francisco: \u2713 Tour della citt\u00e0 in autobus \u2713 Biglietti per un massimo di 48 ore \u2713 15+ fermate a San Francisco. Per saperne di pi\u00f9 e acquistare i biglietti ora.","canonical_url":"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.hop-on-hop-off.net\/it#listItem","position":1,"name":"Startseite","item":"https:\/\/www.hop-on-hop-off.net\/it","nextItem":{"@type":"ListItem","@id":"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/#listItem","name":"San Francisco: Hop-on\/Hop-off"}},{"@type":"ListItem","@id":"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/#listItem","position":2,"name":"San Francisco: Hop-on\/Hop-off","previousItem":{"@type":"ListItem","@id":"https:\/\/www.hop-on-hop-off.net\/it#listItem","name":"Startseite"}}]},{"@type":"Organization","@id":"https:\/\/www.hop-on-hop-off.net\/it\/#organization","name":"Hop-on\/Hop-off","url":"https:\/\/www.hop-on-hop-off.net\/it\/","logo":{"@type":"ImageObject","url":"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png","@id":"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/#organizationLogo","width":365,"height":70,"caption":"Hop-on\/Hop-off Bus"},"image":{"@id":"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/#webpage","url":"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/","name":"San Francisco: Hop-on\/Hop-off - Routen & Fahrpl\u00e4ne 2026","description":"Hop-on\/Hop-off San Francisco: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu 48 Stunden \u2713 15+ Haltestellen in San Francisco. Jetzt informieren und Tickets kaufen.","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.hop-on-hop-off.net\/it\/#website"},"breadcrumb":{"@id":"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/#breadcrumblist"},"datePublished":"2023-11-17T13:48:17+00:00","dateModified":"2026-05-12T07:47:21+00:00"},{"@type":"WebSite","@id":"https:\/\/www.hop-on-hop-off.net\/it\/#website","url":"https:\/\/www.hop-on-hop-off.net\/it\/","name":"Hop-on\/Hop-off","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.hop-on-hop-off.net\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Hop-on\/Hop-off.net -","og:type":"article","og:title":"San Francisco: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne 2026","og:description":"Hop-on\/Hop-off San Francisco: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu 48 Stunden \u2713 15+ Haltestellen in San Francisco. Jetzt informieren und Tickets kaufen.","og:url":"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/","og:image":"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png","og:image:secure_url":"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png","article:published_time":"2023-11-17T13:48:17+00:00","article:modified_time":"2026-05-12T07:47:21+00:00","twitter:card":"summary_large_image","twitter:title":"San Francisco: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne 2026","twitter:description":"Hop-on\/Hop-off San Francisco: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu 48 Stunden \u2713 15+ Haltestellen in San Francisco. Jetzt informieren und Tickets kaufen.","twitter:image":"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png"},"aioseo_meta_data":{"post_id":"1201","title":"San Francisco: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne #current_year","description":"Hop-on\/Hop-off San Francisco: \u2713 Tour della citt\u00e0 in autobus \u2713 Biglietti per un massimo di 48 ore \u2713 15+ fermate a San Francisco. Per saperne di pi\u00f9 e acquistare i biglietti ora.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-11-17 12:04:10","updated":"2026-05-12 09:11:47","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.hop-on-hop-off.net\/it\" title=\"Startseite\">Startseite<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSan Francisco: Hop-on\/Hop-off\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Startseite","link":"https:\/\/www.hop-on-hop-off.net\/it"},{"label":"San Francisco: Hop-on\/Hop-off","link":"https:\/\/www.hop-on-hop-off.net\/it\/san-francisco\/"}],"featured_image_src":null,"_links":{"self":[{"href":"https:\/\/www.hop-on-hop-off.net\/it\/wp-json\/wp\/v2\/pages\/1201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hop-on-hop-off.net\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hop-on-hop-off.net\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hop-on-hop-off.net\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hop-on-hop-off.net\/it\/wp-json\/wp\/v2\/comments?post=1201"}],"version-history":[{"count":27,"href":"https:\/\/www.hop-on-hop-off.net\/it\/wp-json\/wp\/v2\/pages\/1201\/revisions"}],"predecessor-version":[{"id":2941,"href":"https:\/\/www.hop-on-hop-off.net\/it\/wp-json\/wp\/v2\/pages\/1201\/revisions\/2941"}],"wp:attachment":[{"href":"https:\/\/www.hop-on-hop-off.net\/it\/wp-json\/wp\/v2\/media?parent=1201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}