{"id":768,"date":"2023-10-23T11:56:11","date_gmt":"2023-10-23T11:56:11","guid":{"rendered":"https:\/\/www.hop-on-hop-off.net\/?page_id=768"},"modified":"2026-04-28T06:48:13","modified_gmt":"2026-04-28T06:48:13","slug":"kopenhagen","status":"publish","type":"page","link":"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/","title":{"rendered":"Kopenhagen: Hop-on\/Hop-off"},"content":{"rendered":"<style>.kb-image768_a7d7e8-3e .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image768_a7d7e8-3e size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"501\" src=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/10\/copenhagen-red-sightseeing.jpg\" alt=\"Hop-on\/ Hop-off Kopenhagen: Red Sightseeing\" class=\"kb-img wp-image-772\" srcset=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/10\/copenhagen-red-sightseeing.jpg 800w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/10\/copenhagen-red-sightseeing-300x188.jpg 300w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/10\/copenhagen-red-sightseeing-768x481.jpg 768w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/10\/copenhagen-red-sightseeing-18x12.jpg 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>\u00a9 LightField Studios\/ Shutterstock<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Hier finden Sie Informationen zu Stadtrundfahrten mit dem Hop-on\/Hop-off-Bus in Kopenhagen. Wir informieren Sie \u00fcber Anbieter, Haltestellen, Fahrpl\u00e4ne und Preise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Tickets k\u00f6nnen Sie direkt bei unseren Partnern buchen und auf Ihr Handy laden. F\u00fcr den Verkauf erhalten wir eine kleine Provision. Der Preis bleibt f\u00fcr Sie selbstverst\u00e4ndlich gleich.<\/p>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id768_0280ff-33{margin-bottom:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);}.kb-row-layout-id768_0280ff-33 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id768_0280ff-33 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id768_0280ff-33 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id768_0280ff-33 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id768_0280ff-33 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id768_0280ff-33 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id768_0280ff-33 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column768_9e723f-2d > .kt-inside-inner-col,.kadence-column768_9e723f-2d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column768_9e723f-2d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column768_9e723f-2d > .kt-inside-inner-col{flex-direction:column;}.kadence-column768_9e723f-2d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column768_9e723f-2d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column768_9e723f-2d{position:relative;}@media all and (max-width: 1024px){.kadence-column768_9e723f-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column768_9e723f-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column768_9e723f-2d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading768_7c6a75-83, .wp-block-kadence-advancedheading.kt-adv-heading768_7c6a75-83[data-kb-block=\"kb-adv-heading768_7c6a75-83\"]{text-align:center;font-style:normal;background-color:#b51310;border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}.wp-block-kadence-advancedheading.kt-adv-heading768_7c6a75-83 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading768_7c6a75-83[data-kb-block=\"kb-adv-heading768_7c6a75-83\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading768_7c6a75-83 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading768_7c6a75-83[data-kb-block=\"kb-adv-heading768_7c6a75-83\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading768_7c6a75-83, .wp-block-kadence-advancedheading.kt-adv-heading768_7c6a75-83[data-kb-block=\"kb-adv-heading768_7c6a75-83\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading768_7c6a75-83, .wp-block-kadence-advancedheading.kt-adv-heading768_7c6a75-83[data-kb-block=\"kb-adv-heading768_7c6a75-83\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}<\/style>\n<h2 id=\"0-valencia-bus-tur%C3%ADstic\" class=\"kt-adv-heading768_7c6a75-83 wp-block-kadence-advancedheading has-base-3-color has-text-color\" data-kb-block=\"kb-adv-heading768_7c6a75-83\">Str\u00f8mma &amp; City Sightseeing<\/h2>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id768_6a783d-bb{margin-bottom:0px;}.kb-row-layout-id768_6a783d-bb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id768_6a783d-bb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id768_6a783d-bb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id768_6a783d-bb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id768_6a783d-bb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id768_6a783d-bb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id768_6a783d-bb alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column768_cbc8dd-04 > .kt-inside-inner-col,.kadence-column768_cbc8dd-04 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column768_cbc8dd-04 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column768_cbc8dd-04 > .kt-inside-inner-col{flex-direction:column;}.kadence-column768_cbc8dd-04 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column768_cbc8dd-04 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column768_cbc8dd-04{position:relative;}@media all and (max-width: 1024px){.kadence-column768_cbc8dd-04 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column768_cbc8dd-04 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column768_cbc8dd-04\"><div class=\"kt-inside-inner-col\"><style>.kadence-column768_0133f4-c0 > .kt-inside-inner-col,.kadence-column768_0133f4-c0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column768_0133f4-c0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column768_0133f4-c0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column768_0133f4-c0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column768_0133f4-c0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column768_0133f4-c0{position:relative;}.kadence-column768_0133f4-c0, .kt-inside-inner-col > .kadence-column768_0133f4-c0:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column768_0133f4-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column768_0133f4-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column768_0133f4-c0\"><div class=\"kt-inside-inner-col\">\n<div data-tiqets-widget=\"availability\" data-layout=\"full\" data-orientation=\"horizontal\" data-product-id=\"1043398\" data-partner=\"hopon\"><\/div>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading768_0f9e2f-f4, .wp-block-kadence-advancedheading.kt-adv-heading768_0f9e2f-f4[data-kb-block=\"kb-adv-heading768_0f9e2f-f4\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading768_0f9e2f-f4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading768_0f9e2f-f4[data-kb-block=\"kb-adv-heading768_0f9e2f-f4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading768_0f9e2f-f4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading768_0f9e2f-f4[data-kb-block=\"kb-adv-heading768_0f9e2f-f4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p id=\"1-valencia-bus-turistic-bietet-seit-1999-stadtrundfahrten-an-die-roten-hop-onhop-off-busse-bedienen-haltestellen-die-%C3%BCber-ganz-valencia-verteilt-sind-an-bord-gibt-es-einen-audioguide-in-10-sprachen\" class=\"kt-adv-heading768_0f9e2f-f4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading768_0f9e2f-f4\">Sowohl Str\u00f8mma als auch City Sightseeing sind bekannte Anbieter von Hop-on-Hop-off-Touren.<\/p>\n\n\n<style>.kadence-column768_0c4205-be > .kt-inside-inner-col,.kadence-column768_0c4205-be > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column768_0c4205-be > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column768_0c4205-be > .kt-inside-inner-col{flex-direction:column;}.kadence-column768_0c4205-be > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column768_0c4205-be > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column768_0c4205-be{position:relative;}.kadence-column768_0c4205-be, .kt-inside-inner-col > .kadence-column768_0c4205-be:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column768_0c4205-be > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column768_0c4205-be > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column768_0c4205-be\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id768_664865-95 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:5px;}.kt-accordion-id768_664865-95 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id768_664865-95 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:var(--contrast);padding-top:10px;padding-right:14px;padding-bottom:10px;padding-left:14px;}.kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--contrast);}.kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--contrast);}.kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id768_664865-95 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id768_664865-95 .kt-blocks-accordion-header:focus-visible{color:#444444;background:var(--base-2);border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--base-2);}.kt-accordion-id768_664865-95 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id768_664865-95 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#e51b22;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id768_664865-95:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#e51b22;}@media all and (max-width: 1024px){.kt-accordion-id768_664865-95 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id768_664865-95 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id768_664865-95 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id768_664865-95 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id768_664865-95 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id768_664865-95 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id768_664865-95 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id768_664865-95 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:5px;}.kt-accordion-id768_664865-95 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id768_664865-95 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id768_664865-95 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id768_664865-95 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id768_664865-95 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id768_664865-95 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id768_664865-95 kt-accordion-has-7-panes kt-active-pane-3 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane768_e4cb08-10\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Routen &amp; Haltestellen<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items768_f21684-a8:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_f21684-a8 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_f21684-a8 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_f21684-a8 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_f21684-a8 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items768_f21684-a8 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items768_f21684-a8 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-768_694490-97 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_694490-97\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">3 Routen \u2013&nbsp;30 Haltestellen<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_a9c1b3-d2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_a9c1b3-d2\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Start-Haltestelle: Tivoli<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_765cf5-66 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_765cf5-66\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">optionale Bootsfahrt<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_d68bb8-da .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_d68bb8-da\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/www.stromma.com\/de-dk\/copenhagen\/sightseeing\/sightseeing-by-bus\/hop-on-hop-off\/\" target=\"_blank\" rel=\"noopener\" title=\"\">Karte mit Route &amp; Haltestellen<\/a><\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane768_a3eddb-ae\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Fahrplan Route: Classic Copenhagen<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items768_954a83-35:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_954a83-35 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_954a83-35 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_954a83-35 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_954a83-35 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items768_954a83-35 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items768_954a83-35 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-768_ddc292-5e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_ddc292-5e\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Erste Abfahrt: 10:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_d6e7ff-71 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_d6e7ff-71\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Letzte Abfahrt: 16:30<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_72635d-79 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_72635d-79\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Frequenz: alle 30-35 Minuten<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_13aad2-b8 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_13aad2-b8\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Dauer: 80 Minuten<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane768_4c88fe-f7\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Fahrplan Route: Home of Carlsberg<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items768_083c2b-10:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_083c2b-10 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_083c2b-10 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_083c2b-10 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_083c2b-10 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items768_083c2b-10 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items768_083c2b-10 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-768_55e180-4f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_55e180-4f\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">T\u00e4glich 11:15, 13:15 und 15:15 Uhr<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-7 kt-pane768_838b51-50\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Fahrplan Route: Colorful Copenhagen<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items768_2bed70-da:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_2bed70-da ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_2bed70-da ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_2bed70-da .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_2bed70-da ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items768_2bed70-da ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items768_2bed70-da kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-768_29af8e-8b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_29af8e-8b\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">T\u00e4glich 12:00, 14:00 und 16:00<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane768_f8f4be-98\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Kontakt: Str\u00f8mma Kopenhagen<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading768_9e2b79-d2, .wp-block-kadence-advancedheading.kt-adv-heading768_9e2b79-d2[data-kb-block=\"kb-adv-heading768_9e2b79-d2\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading768_9e2b79-d2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading768_9e2b79-d2[data-kb-block=\"kb-adv-heading768_9e2b79-d2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading768_9e2b79-d2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading768_9e2b79-d2[data-kb-block=\"kb-adv-heading768_9e2b79-d2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading768_9e2b79-d2 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading768_9e2b79-d2\">Sollten Sie Fragen an das Unternehmen haben oder sich beschweren wollen, k\u00f6nnen Sie Str\u00f8mma Kopenhagen per E-Mail oder Telefon kontaktieren:<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items768_a05dcb-95:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_a05dcb-95 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_a05dcb-95 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_a05dcb-95 .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_a05dcb-95 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items768_a05dcb-95 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items768_a05dcb-95 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-768_3846bc-11 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_3846bc-11\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mail kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M4 4h16c1.1 0 2 .9 2 2v12c0 1.1-.9 2-2 2H4c-1.1 0-2-.9-2-2V6c0-1.1.9-2 2-2z\"\/><polyline points=\"22,6 12,13 2,6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Mail: info@stromma.dk<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_010ba3-35 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_010ba3-35\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_phone kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 16.92v3a2 2 0 0 1-2.18 2 19.79 19.79 0 0 1-8.63-3.07 19.5 19.5 0 0 1-6-6 19.79 19.79 0 0 1-3.07-8.67A2 2 0 0 1 4.11 2h3a2 2 0 0 1 2 1.72 12.84 12.84 0 0 0 .7 2.81 2 2 0 0 1-.45 2.11L8.09 9.91a16 16 0 0 0 6 6l1.27-1.27a2 2 0 0 1 2.11-.45 12.84 12.84 0 0 0 2.81.7A2 2 0 0 1 22 16.92z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Telefon: +45 32 96 30 00<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading768_9dc2e6-a3, .wp-block-kadence-advancedheading.kt-adv-heading768_9dc2e6-a3[data-kb-block=\"kb-adv-heading768_9dc2e6-a3\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading768_9dc2e6-a3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading768_9dc2e6-a3[data-kb-block=\"kb-adv-heading768_9dc2e6-a3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading768_9dc2e6-a3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading768_9dc2e6-a3[data-kb-block=\"kb-adv-heading768_9dc2e6-a3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading768_9dc2e6-a3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading768_9dc2e6-a3\">Wenn Sie Fragen zur Ticketbuchung haben, wenden Sie sich bitte an den Kundenservice von Tiqets.com oder GetYourGuide (je nachdem, wo Sie Ihr Ticket gebucht haben).<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend der Fahrt steht ein Audioguide in 11 Sprachen zur Verf\u00fcgung, der \u00fcber Wissenswertes \u00fcber die Stadt und ihre Sehensw\u00fcrdigkeiten informiert.<\/p>\n\n\n<p><strong>Ticketg\u00fcltigkeit:<\/strong> 24-72 Stunden<br \/>\n<strong>Bewertung:<\/strong> 3,9 (26 Reviews)<br \/>\n<strong>Preis 72h-Ticket:<\/strong> 42,00 EUR<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns768_e8a5af-43{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns768_e8a5af-43 .kt-button{font-weight:normal;font-style:normal;}.kt-btns768_e8a5af-43 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns768_e8a5af-43 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns768_e8a5af-43 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns768_e8a5af-43 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns768_e8a5af-43 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns768_e8a5af-43 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns768_e8a5af-43 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns768_e8a5af-43\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn768_b0f9bc-6c.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn768_b0f9bc-6c.kb-button{color:var(--base-3);background:#e51b22;box-shadow:2px 2px 2px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn768_b0f9bc-6c.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn768_b0f9bc-6c.kb-button:focus{color:var(--base-3);background:#b51310;}<\/style><a class=\"kb-button kt-button button kb-btn768_b0f9bc-6c kt-btn-size-large kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/www.tiqets.com\/de\/checkout\/tickets-fur-classic-route-open-top-bus-hop-on-hop-off-copenhagen-p1043398\/booking_details\/?partner=hopon\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_externalLink kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Tickets kaufen<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading768_02fd7a-57, .wp-block-kadence-advancedheading.kt-adv-heading768_02fd7a-57[data-kb-block=\"kb-adv-heading768_02fd7a-57\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading768_02fd7a-57 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading768_02fd7a-57[data-kb-block=\"kb-adv-heading768_02fd7a-57\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading768_02fd7a-57 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading768_02fd7a-57[data-kb-block=\"kb-adv-heading768_02fd7a-57\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading768_02fd7a-57 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading768_02fd7a-57\">Wenn Sie Ihr Busticket online kaufen, erhalten Sie einen Voucher, den Sie auf Ihrem Handy speichern k\u00f6nnen. Zeigen Sie Ihren digitalen Voucher dem Buspersonal, wenn Sie zum ersten Mal in den Bus einsteigen. Sie erhalten dann Ihr Ticket, das je nach gebuchter Option 24 bis 72 Stunden ab der ersten Fahrt g\u00fcltig ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hier finden Sie weitere beliebte Ticketoptionen:<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items768_2f5556-b5:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_2f5556-b5 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_2f5556-b5 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_2f5556-b5 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items768_2f5556-b5 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items768_2f5556-b5 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-768_66d16f-71 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_66d16f-71\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_shoppingCart kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"9\" cy=\"21\" r=\"1\"\/><circle cx=\"20\" cy=\"21\" r=\"1\"\/><path d=\"M1 1h4l2.68 13.39a2 2 0 0 0 2 1.61h9.72a2 2 0 0 0 2-1.61L23 6H6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/www.getyourguide.de\/kopenhagen-l12\/kopenhagen-bus-boot-hop-onhop-off-24-stunden-pass-t21339\/?partner_id=B0910&amp;cmp=hopon&amp;mkt_cmp=true\" target=\"_blank\" rel=\"noopener nofollow sponsored\" title=\"\">48 Stunden Bus und Boot<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_352756-67 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_352756-67\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_shoppingCart kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"9\" cy=\"21\" r=\"1\"\/><circle cx=\"20\" cy=\"21\" r=\"1\"\/><path d=\"M1 1h4l2.68 13.39a2 2 0 0 0 2 1.61h9.72a2 2 0 0 0 2-1.61L23 6H6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/www.tiqets.com\/de\/checkout\/tickets-fur-hop-on-hop-off-bus-copenhagen-all-routes-p1058211\/booking_details\/?partner=hopon\" target=\"_blank\" rel=\"noopener nofollow sponsored\" title=\"\">72 Stunden f\u00fcr alle Routen<\/a><\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id768_42b872-e3{margin-bottom:0px;margin-bottom:var(--global-kb-spacing-xs, 1rem);}.kb-row-layout-id768_42b872-e3 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id768_42b872-e3 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id768_42b872-e3 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id768_42b872-e3 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id768_42b872-e3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id768_42b872-e3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id768_42b872-e3 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column768_778d2e-d6 > .kt-inside-inner-col,.kadence-column768_778d2e-d6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column768_778d2e-d6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column768_778d2e-d6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column768_778d2e-d6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column768_778d2e-d6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column768_778d2e-d6{position:relative;}@media all and (max-width: 1024px){.kadence-column768_778d2e-d6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column768_778d2e-d6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column768_778d2e-d6\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading768_b570e7-26, .wp-block-kadence-advancedheading.kt-adv-heading768_b570e7-26[data-kb-block=\"kb-adv-heading768_b570e7-26\"]{text-align:center;font-style:normal;background-color:#b51310;border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}.wp-block-kadence-advancedheading.kt-adv-heading768_b570e7-26 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading768_b570e7-26[data-kb-block=\"kb-adv-heading768_b570e7-26\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading768_b570e7-26 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading768_b570e7-26[data-kb-block=\"kb-adv-heading768_b570e7-26\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading768_b570e7-26, .wp-block-kadence-advancedheading.kt-adv-heading768_b570e7-26[data-kb-block=\"kb-adv-heading768_b570e7-26\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading768_b570e7-26, .wp-block-kadence-advancedheading.kt-adv-heading768_b570e7-26[data-kb-block=\"kb-adv-heading768_b570e7-26\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}<\/style>\n<h2 id=\"0-valencia-bus-tur%C3%ADstic\" class=\"kt-adv-heading768_b570e7-26 wp-block-kadence-advancedheading has-base-3-color has-text-color\" data-kb-block=\"kb-adv-heading768_b570e7-26\">Red Sightseeing<\/h2>\n\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id768_17c8d1-db{margin-bottom:0px;}.kb-row-layout-id768_17c8d1-db > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id768_17c8d1-db > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id768_17c8d1-db > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id768_17c8d1-db > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id768_17c8d1-db > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id768_17c8d1-db > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id768_17c8d1-db alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column768_b69dfe-ed > .kt-inside-inner-col,.kadence-column768_b69dfe-ed > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column768_b69dfe-ed > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column768_b69dfe-ed > .kt-inside-inner-col{flex-direction:column;}.kadence-column768_b69dfe-ed > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column768_b69dfe-ed > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column768_b69dfe-ed{position:relative;}@media all and (max-width: 1024px){.kadence-column768_b69dfe-ed > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column768_b69dfe-ed > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column768_b69dfe-ed\"><div class=\"kt-inside-inner-col\"><style>.kadence-column768_2ff9e8-42 > .kt-inside-inner-col,.kadence-column768_2ff9e8-42 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column768_2ff9e8-42 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column768_2ff9e8-42 > .kt-inside-inner-col{flex-direction:column;}.kadence-column768_2ff9e8-42 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column768_2ff9e8-42 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column768_2ff9e8-42{position:relative;}.kadence-column768_2ff9e8-42, .kt-inside-inner-col > .kadence-column768_2ff9e8-42:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column768_2ff9e8-42 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column768_2ff9e8-42 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column768_2ff9e8-42\"><div class=\"kt-inside-inner-col\">\n<div data-tiqets-widget=\"availability\" data-layout=\"full\" data-orientation=\"horizontal\" data-product-id=\"975081\" data-partner=\"hopon\"><\/div>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading768_c8daa0-e7, .wp-block-kadence-advancedheading.kt-adv-heading768_c8daa0-e7[data-kb-block=\"kb-adv-heading768_c8daa0-e7\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading768_c8daa0-e7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading768_c8daa0-e7[data-kb-block=\"kb-adv-heading768_c8daa0-e7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading768_c8daa0-e7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading768_c8daa0-e7[data-kb-block=\"kb-adv-heading768_c8daa0-e7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p id=\"1-valencia-bus-turistic-bietet-seit-1999-stadtrundfahrten-an-die-roten-hop-onhop-off-busse-bedienen-haltestellen-die-%C3%BCber-ganz-valencia-verteilt-sind-an-bord-gibt-es-einen-audioguide-in-10-sprachen\" class=\"kt-adv-heading768_c8daa0-e7 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading768_c8daa0-e7\">Mit einem klassischen roten Doppeldeckerbus f\u00e4hrt Red Sightseeing Sie auf einer Route durch Kopenhagen.<\/p>\n\n\n<style>.kadence-column768_7f9ed5-09 > .kt-inside-inner-col,.kadence-column768_7f9ed5-09 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column768_7f9ed5-09 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column768_7f9ed5-09 > .kt-inside-inner-col{flex-direction:column;}.kadence-column768_7f9ed5-09 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column768_7f9ed5-09 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column768_7f9ed5-09{position:relative;}.kadence-column768_7f9ed5-09, .kt-inside-inner-col > .kadence-column768_7f9ed5-09:not(.specificity){margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}@media all and (max-width: 1024px){.kadence-column768_7f9ed5-09 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column768_7f9ed5-09 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column768_7f9ed5-09\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id768_fc6d69-41 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:5px;}.kt-accordion-id768_fc6d69-41 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id768_fc6d69-41 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:var(--contrast);padding-top:10px;padding-right:14px;padding-bottom:10px;padding-left:14px;}.kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--contrast);}.kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--contrast);}.kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id768_fc6d69-41 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id768_fc6d69-41 .kt-blocks-accordion-header:focus-visible{color:#444444;background:var(--base-2);border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--base-2);}.kt-accordion-id768_fc6d69-41 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id768_fc6d69-41 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#e51b22;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id768_fc6d69-41:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#e51b22;}@media all and (max-width: 1024px){.kt-accordion-id768_fc6d69-41 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id768_fc6d69-41 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id768_fc6d69-41 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id768_fc6d69-41 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id768_fc6d69-41 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id768_fc6d69-41 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id768_fc6d69-41 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id768_fc6d69-41 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:5px;}.kt-accordion-id768_fc6d69-41 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id768_fc6d69-41 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id768_fc6d69-41 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id768_fc6d69-41 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id768_fc6d69-41 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id768_fc6d69-41 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id768_fc6d69-41 kt-accordion-has-7-panes kt-active-pane-3 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane768_fd74f0-09\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Routen &amp; Haltestellen<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items768_63f754-ad:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_63f754-ad ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_63f754-ad ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_63f754-ad .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_63f754-ad ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items768_63f754-ad ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items768_63f754-ad kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-768_5a869d-29 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_5a869d-29\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">1 Route \u2013&nbsp;18 Haltestellen<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_ea74b1-df .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_ea74b1-df\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Start-Haltestelle: Hauptbahnhof \/ Tivoli-G\u00e4rten<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_df0805-99 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_df0805-99\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">optionale Bootsfahrt<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_330e2b-ac .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_330e2b-ac\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"https:\/\/www.redsightseeing.com\/media\/jdpfz3jz\/map-2025.pdf\" target=\"_blank\" rel=\"noopener\" title=\"\">Karte mit Route &amp; Haltestellen<\/a><\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane768_d5dea3-44\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Fahrplan <\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items768_9fdc10-3e:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_9fdc10-3e ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_9fdc10-3e ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_9fdc10-3e .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_9fdc10-3e ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items768_9fdc10-3e ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items768_9fdc10-3e kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-768_3082a3-f8 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_3082a3-f8\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Erste Abfahrt: 09:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_ba2989-1e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_ba2989-1e\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Letzte Abfahrt: 17:00<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_ac1399-96 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_ac1399-96\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Frequenz: alle 10-45 Minuten<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_b1bf81-5b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_b1bf81-5b\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Dauer: 90 Minuten<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane768_1d546c-b2\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Kontakt: Red Sightseeing<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading768_81edf4-b1, .wp-block-kadence-advancedheading.kt-adv-heading768_81edf4-b1[data-kb-block=\"kb-adv-heading768_81edf4-b1\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading768_81edf4-b1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading768_81edf4-b1[data-kb-block=\"kb-adv-heading768_81edf4-b1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading768_81edf4-b1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading768_81edf4-b1[data-kb-block=\"kb-adv-heading768_81edf4-b1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading768_81edf4-b1 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading768_81edf4-b1\">Sollten Sie Fragen an das Unternehmen haben oder sich beschweren wollen, k\u00f6nnen Sie Red Sightseeing Kopenhagen per E-Mail oder Telefon kontaktieren:<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items768_b81113-2f:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_b81113-2f ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_b81113-2f ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_b81113-2f .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_b81113-2f ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items768_b81113-2f ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items768_b81113-2f kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-768_f5be72-f6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_f5be72-f6\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mail kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M4 4h16c1.1 0 2 .9 2 2v12c0 1.1-.9 2-2 2H4c-1.1 0-2-.9-2-2V6c0-1.1.9-2 2-2z\"\/><polyline points=\"22,6 12,13 2,6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Mail: copenhagen@redsightseeing.com<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_08e091-63 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_08e091-63\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_phone kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 16.92v3a2 2 0 0 1-2.18 2 19.79 19.79 0 0 1-8.63-3.07 19.5 19.5 0 0 1-6-6 19.79 19.79 0 0 1-3.07-8.67A2 2 0 0 1 4.11 2h3a2 2 0 0 1 2 1.72 12.84 12.84 0 0 0 .7 2.81 2 2 0 0 1-.45 2.11L8.09 9.91a16 16 0 0 0 6 6l1.27-1.27a2 2 0 0 1 2.11-.45 12.84 12.84 0 0 0 2.81.7A2 2 0 0 1 22 16.92z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Telefon: +45 31 34 44 12<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading768_2edeb8-3c, .wp-block-kadence-advancedheading.kt-adv-heading768_2edeb8-3c[data-kb-block=\"kb-adv-heading768_2edeb8-3c\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading768_2edeb8-3c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading768_2edeb8-3c[data-kb-block=\"kb-adv-heading768_2edeb8-3c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading768_2edeb8-3c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading768_2edeb8-3c[data-kb-block=\"kb-adv-heading768_2edeb8-3c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading768_2edeb8-3c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading768_2edeb8-3c\">Wenn Sie Fragen zur Ticketbuchung haben, wenden Sie sich bitte an den Kundenservice von Tiqets.com oder GetYourGuide (je nachdem, wo Sie Ihr Ticket gebucht haben).<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Im Bus steht Ihnen neben kostenlosem Wifi auch ein mehrsprachiger Audioguide zur Verf\u00fcgung. <\/p>\n\n\n<p><strong>Ticketg\u00fcltigkeit:<\/strong> 24-48 Stunden<br \/>\n<strong>Bewertung:<\/strong> 4,0 (104 Reviews)<br \/>\n<strong>Preis:<\/strong> ab 30,00 EUR<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns768_f9ce7c-e3{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns768_f9ce7c-e3 .kt-button{font-weight:normal;font-style:normal;}.kt-btns768_f9ce7c-e3 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns768_f9ce7c-e3 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns768_f9ce7c-e3 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns768_f9ce7c-e3 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns768_f9ce7c-e3 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns768_f9ce7c-e3 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns768_f9ce7c-e3 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns768_f9ce7c-e3\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn768_349ce8-ac.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn768_349ce8-ac.kb-button{color:var(--base-3);background:#e51b22;box-shadow:2px 2px 2px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn768_349ce8-ac.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn768_349ce8-ac.kb-button:focus{color:var(--base-3);background:#b51310;}<\/style><a class=\"kb-button kt-button button kb-btn768_349ce8-ac kt-btn-size-large kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/www.tiqets.com\/de\/checkout\/tickets-fur-red-sightseeing-kopenhagen-hop-on-hop-off-bus-tour-p975081\/booking_details\/?partner=hopon\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_externalLink kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Tickets kaufen<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading768_9c03cd-cc, .wp-block-kadence-advancedheading.kt-adv-heading768_9c03cd-cc[data-kb-block=\"kb-adv-heading768_9c03cd-cc\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading768_9c03cd-cc mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading768_9c03cd-cc[data-kb-block=\"kb-adv-heading768_9c03cd-cc\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading768_9c03cd-cc img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading768_9c03cd-cc[data-kb-block=\"kb-adv-heading768_9c03cd-cc\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading768_9c03cd-cc wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading768_9c03cd-cc\">Wenn Sie Ihr Busticket online kaufen, erhalten Sie einen Voucher, den Sie auf Ihrem Handy speichern k\u00f6nnen. Zeigen Sie Ihren digitalen Voucher dem Buspersonal, wenn Sie zum ersten Mal in den Bus einsteigen. Sie erhalten dann Ihr Ticket, das je nach gebuchter Option 24 bis 48 Stunden ab der ersten Fahrt g\u00fcltig ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tipp:<\/strong> Mit einem Kombiticket k\u00f6nnen Sie etwas Geld sparen. <a href=\"https:\/\/www.tiqets.com\/de\/checkout\/tickets-fur-red-sightseeing-copenhagen-hop-on-hop-off-bus-and-boat-tour-p1059428\/booking_details\/?partner=hopon\" target=\"_blank\" rel=\"noopener nofollow sponsored\" title=\"\">24 Stunden Bus + Kanalfahrt<\/a><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id768_fcbfab-82{margin-bottom:0px;margin-bottom:var(--global-kb-spacing-md, 2rem);}.kb-row-layout-id768_fcbfab-82 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id768_fcbfab-82 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id768_fcbfab-82 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id768_fcbfab-82 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id768_fcbfab-82 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id768_fcbfab-82 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id768_fcbfab-82 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column768_c9236c-d5 > .kt-inside-inner-col,.kadence-column768_c9236c-d5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column768_c9236c-d5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column768_c9236c-d5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column768_c9236c-d5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column768_c9236c-d5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column768_c9236c-d5{position:relative;}@media all and (max-width: 1024px){.kadence-column768_c9236c-d5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column768_c9236c-d5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column768_c9236c-d5\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading768_f53a4b-c5, .wp-block-kadence-advancedheading.kt-adv-heading768_f53a4b-c5[data-kb-block=\"kb-adv-heading768_f53a4b-c5\"]{font-style:normal;background-color:#b51310;border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}.wp-block-kadence-advancedheading.kt-adv-heading768_f53a4b-c5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading768_f53a4b-c5[data-kb-block=\"kb-adv-heading768_f53a4b-c5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading768_f53a4b-c5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading768_f53a4b-c5[data-kb-block=\"kb-adv-heading768_f53a4b-c5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading768_f53a4b-c5, .wp-block-kadence-advancedheading.kt-adv-heading768_f53a4b-c5[data-kb-block=\"kb-adv-heading768_f53a4b-c5\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading768_f53a4b-c5, .wp-block-kadence-advancedheading.kt-adv-heading768_f53a4b-c5[data-kb-block=\"kb-adv-heading768_f53a4b-c5\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}<\/style>\n<h2 id=\"11-hop-onhop-off-sehensw%C3%BCrdigkeiten\" class=\"kt-adv-heading768_f53a4b-c5 wp-block-kadence-advancedheading has-base-3-color has-text-color\" data-kb-block=\"kb-adv-heading768_f53a4b-c5\">Hop-on\/Hop-off: Sehensw\u00fcrdigkeiten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Kopenhagen, die Hauptstadt D\u00e4nemarks, ist bekannt f\u00fcr ihre innovative Architektur, ihre kulinarische Szene und kulturelle Vielfalt. Die wichtigsten Sehensw\u00fcrdigkeiten sind mit dem Hop-on\/Hop-off-Bus zu erreichen:<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items768_a4e939-3c:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_a4e939-3c ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_a4e939-3c ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_a4e939-3c .kb-svg-icon-wrap{font-size:20px;color:#b51310;}.wp-block-kadence-iconlist.kt-svg-icon-list-items768_a4e939-3c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items768_a4e939-3c ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}@media all and (min-width: 1025px){.wp-block-kadence-iconlist.kt-svg-icon-list-items768_a4e939-3c:not(.kt-svg-icon-list-columns-1) ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap:not(:last-child){margin:0px;}}@media all and (min-width: 768px) and (max-width: 1024px){.wp-block-kadence-iconlist.kt-svg-icon-list-items768_a4e939-3c:not(.kt-tablet-svg-icon-list-columns-1) ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap:not(:last-child){margin:0px;}}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items768_a4e939-3c kt-svg-icon-list-columns-2 alignnone kt-mobile-svg-icon-list-columns-1\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-768_b033dd-ce .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_b033dd-ce\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Die kleine Meerjungfrau<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_67f37c-66 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_67f37c-66\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Der Runde Turm<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_7851df-98 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_7851df-98\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Nyhavn<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_514c04-f0 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_514c04-f0\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Freistadt Christiania<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_7acf2c-2f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_7acf2c-2f\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Tivoli Vergn\u00fcgungspark<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_8d77da-f0 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_8d77da-f0\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Nationalmuseum<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_bb8ffb-30 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_bb8ffb-30\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Schloss Christiansborg<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_42bad5-f5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_42bad5-f5\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">D\u00e4nisch-J\u00fcdisches Museum<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_1e2f93-84 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_1e2f93-84\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Erl\u00f6serkirche<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-768_53f67d-2a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-768_53f67d-2a\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkSquare kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 11 12 14 22 4\"\/><path d=\"M21 12v7a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2h11\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">K\u00f6nigliche Bibliothek<\/span><\/li>\n<\/ul><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Entlang der Route k\u00f6nnen Sie an allen Haltestellen beliebig oft ein- und aussteigen. Nicht alle Haltestellen sind nach den Sehensw\u00fcrdigkeiten benannt. In der Regel sind sie aber durch einen kurzen Fu\u00dfweg leicht zu erreichen.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns768_882bf3-2e{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns768_882bf3-2e .kt-button{font-weight:normal;font-style:normal;}.kt-btns768_882bf3-2e .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns768_882bf3-2e .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns768_882bf3-2e .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns768_882bf3-2e .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns768_882bf3-2e .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns768_882bf3-2e .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns768_882bf3-2e .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns768_882bf3-2e\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn768_6d4bf9-6c.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn768_6d4bf9-6c.kb-button{color:var(--base-3);background:#e51b22;box-shadow:2px 2px 2px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn768_6d4bf9-6c.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn768_6d4bf9-6c.kb-button:focus{color:var(--base-3);background:#b51310;}<\/style><a class=\"kb-button kt-button button kb-btn768_6d4bf9-6c kt-btn-size-large kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/www.tiqets.com\/de\/checkout\/tickets-fur-classic-route-open-top-bus-hop-on-hop-off-copenhagen-p1043398\/booking_details\/?partner=hopon\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_externalLink kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Tickets kaufen<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id768_1a78e9-cb{margin-bottom:0px;}.kb-row-layout-id768_1a78e9-cb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id768_1a78e9-cb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id768_1a78e9-cb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id768_1a78e9-cb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id768_1a78e9-cb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id768_1a78e9-cb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id768_1a78e9-cb alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column768_ee5ffc-05 > .kt-inside-inner-col,.kadence-column768_ee5ffc-05 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column768_ee5ffc-05 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column768_ee5ffc-05 > .kt-inside-inner-col{flex-direction:column;}.kadence-column768_ee5ffc-05 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column768_ee5ffc-05 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column768_ee5ffc-05{position:relative;}@media all and (max-width: 1024px){.kadence-column768_ee5ffc-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column768_ee5ffc-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column768_ee5ffc-05\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading768_eabf79-8b, .wp-block-kadence-advancedheading.kt-adv-heading768_eabf79-8b[data-kb-block=\"kb-adv-heading768_eabf79-8b\"]{font-style:normal;background-color:#b51310;border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}.wp-block-kadence-advancedheading.kt-adv-heading768_eabf79-8b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading768_eabf79-8b[data-kb-block=\"kb-adv-heading768_eabf79-8b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading768_eabf79-8b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading768_eabf79-8b[data-kb-block=\"kb-adv-heading768_eabf79-8b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading768_eabf79-8b, .wp-block-kadence-advancedheading.kt-adv-heading768_eabf79-8b[data-kb-block=\"kb-adv-heading768_eabf79-8b\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading768_eabf79-8b, .wp-block-kadence-advancedheading.kt-adv-heading768_eabf79-8b[data-kb-block=\"kb-adv-heading768_eabf79-8b\"]{border-top:10px solid transparent;border-right:10px solid transparent;border-bottom:10px solid transparent;border-left:10px solid transparent;}}<\/style>\n<h2 id=\"12-lohnt-sich-eine-valencia-stadtrundfahrt\" class=\"kt-adv-heading768_eabf79-8b wp-block-kadence-advancedheading has-base-3-color has-text-color\" data-kb-block=\"kb-adv-heading768_eabf79-8b\">Lohnt sich eine Kopenhagen-Stadtrundfahrt?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Stadtrundfahrt mit dem Hop-on-Hop-off-Bus ist zweifellos eine der besten M\u00f6glichkeiten, die Sch\u00f6nheit und Vielfalt dieser faszinierenden Stadt zu entdecken. Dieses flexible und bequeme Verkehrsmittel bietet Touristen viele Vorteile, die einen Besuch in Kopenhagen unvergesslich machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Hop-on\/Hop-off-Bus erm\u00f6glicht es Ihnen, Kopenhagens Wahrzeichen in Ihrem eigenen Tempo zu erkunden. Sie k\u00f6nnen so oft ein- und aussteigen, wie Sie m\u00f6chten, um Sehensw\u00fcrdigkeiten wie die kleine Meerjungfrau, das imposante Schloss Amalienborg, den lebhaften Hafen Nyhavn oder den ber\u00fchmten Tivoli zu besuchen. So k\u00f6nnen Sie flexibel entscheiden, an welchen Orten Sie sich etwas mehr Zeit f\u00fcr die Besichtigung nehmen, ohne sich um den Fahrplan k\u00fcmmern zu m\u00fcssen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein weiterer Vorteil des Hop-on-Hop-off-Busses ist der informative Audioguide. W\u00e4hrend der Fahrt erhalten die Fahrg\u00e4ste interessante Einblicke in die Geschichte, Kultur und Architektur der Stadt. Dieses Wissen bereichert nicht nur das Reiseerlebnis, sondern hilft auch, die Hintergr\u00fcnde der besuchten Sehensw\u00fcrdigkeiten besser zu verstehen.<\/p>\n\n\n<style>.kb-image768_5be52a-50 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image768_5be52a-50 size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"501\" src=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/10\/copenhagen-panorama.jpg\" alt=\"Kopenhagen\" class=\"kb-img wp-image-792\" srcset=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/10\/copenhagen-panorama.jpg 800w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/10\/copenhagen-panorama-300x188.jpg 300w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/10\/copenhagen-panorama-768x481.jpg 768w, https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/10\/copenhagen-panorama-18x12.jpg 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>\u00a9 Nick Karvounis\/ Unsplash<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Die Busse selbst sind komfortabel und klimatisiert, was besonders bei Stadtrundfahrten in den hei\u00dfen Sommermonaten sehr angenehm ist. Au\u00dferdem bieten sie eine erh\u00f6hte Sitzposition, die eine hervorragende Aussicht auf die Umgebung erm\u00f6glicht und vor allem f\u00fcr Fotofreunde ein gro\u00dfer Vorteil ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alles in allem sind die Hop-on-Hop-off-Busse in Kopenhagen eine bequeme, flexible und informative Art, die Sch\u00e4tze dieser sch\u00f6nen Stadt zu entdecken. Die M\u00f6glichkeit, die Stadt in aller Ruhe zu erkunden und dabei faszinierende Geschichten zu h\u00f6ren, macht diese Stadtrundfahrt zu einem Muss f\u00fcr jeden Besucher, der das Beste aus seinem Aufenthalt in Kopenhagen machen m\u00f6chte.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns768_3bbb92-7d{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns768_3bbb92-7d .kt-button{font-weight:normal;font-style:normal;}.kt-btns768_3bbb92-7d .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns768_3bbb92-7d .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns768_3bbb92-7d .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns768_3bbb92-7d .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns768_3bbb92-7d .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns768_3bbb92-7d .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns768_3bbb92-7d .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns768_3bbb92-7d\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn768_4fba86-de.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn768_4fba86-de.kb-button{color:var(--base-3);background:#e51b22;box-shadow:2px 2px 2px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn768_4fba86-de.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn768_4fba86-de.kb-button:focus{color:var(--base-3);background:#b51310;}<\/style><a class=\"kb-button kt-button button kb-btn768_4fba86-de kt-btn-size-large kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-true wp-block-kadence-singlebtn\" href=\"https:\/\/www.tiqets.com\/de\/checkout\/tickets-fur-classic-route-open-top-bus-hop-on-hop-off-copenhagen-p1043398\/booking_details\/?partner=hopon\" target=\"_blank\" rel=\"noreferrer noopener nofollow sponsored\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_externalLink kt-btn-icon-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Tickets kaufen<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tipp:<\/strong> Auch andere skandinavische St\u00e4dte wie <a href=\"https:\/\/www.hop-on-hop-off.net\/de\/oslo\/\" target=\"_blank\" rel=\"noopener\" title=\"\">Oslo <\/a>oder <a href=\"https:\/\/www.hop-on-hop-off.net\/de\/reykjavik\/\" target=\"_blank\" rel=\"noopener\" title=\"\">Reykjavik <\/a>kann sehr gut mit dem Hop-on\/Hop-off-Bus besichtigen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hier vind je informatie over sightseeingtours met de hop-on hop-off bus in Kopenhagen. We informeren je over aanbieders, haltes, dienstregelingen en prijzen. Je kunt tickets rechtstreeks bij onze partners boeken en downloaden naar je mobiele telefoon. We ontvangen een kleine commissie voor de verkoop. Natuurlijk blijft de prijs voor jou hetzelfde. Str\u00f8mma &amp; City Sightseeing Zowel Str\u00f8mma ... <a title=\"Kopenhagen: Hop-on\/Hop-off\" class=\"read-more\" href=\"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/\" aria-label=\"Lees meer over Kopenhagen: Hop-on\/Hop-off\">Lees verder<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-768","page","type-page","status-publish"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hop-on\/Hop-off Kopenhagen: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu Stunden \u2713 30+ Haltestellen in Kopenhagen. Jetzt informieren und Tickets kaufen.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"nl_NL\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Hop-on\/Hop-off.net -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Kopenhagen: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne 2026\" \/>\n\t\t<meta property=\"og:description\" content=\"Hop-on\/Hop-off Kopenhagen: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu Stunden \u2713 30+ Haltestellen in Kopenhagen. Jetzt informieren und Tickets kaufen.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-23T11:56:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-28T06:48:13+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Kopenhagen: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne 2026\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Hop-on\/Hop-off Kopenhagen: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu Stunden \u2713 30+ Haltestellen in Kopenhagen. Jetzt informieren und Tickets kaufen.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\\\/kopenhagen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl#listItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\\\/kopenhagen\\\/#listItem\",\"name\":\"Kopenhagen: Hop-on\\\/Hop-off\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\\\/kopenhagen\\\/#listItem\",\"position\":2,\"name\":\"Kopenhagen: Hop-on\\\/Hop-off\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl#listItem\",\"name\":\"Startseite\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\\\/#organization\",\"name\":\"Hop-on\\\/Hop-off\",\"url\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/hop-on-hop-off.png\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\\\/kopenhagen\\\/#organizationLogo\",\"width\":365,\"height\":70,\"caption\":\"Hop-on\\\/Hop-off Bus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\\\/kopenhagen\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\\\/kopenhagen\\\/#webpage\",\"url\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\\\/kopenhagen\\\/\",\"name\":\"Kopenhagen: Hop-on\\\/Hop-off - Routen & Fahrpl\\u00e4ne 2026\",\"description\":\"Hop-on\\\/Hop-off Kopenhagen: \\u2713 Stadtrundfahrt im Bus \\u2713 Tickets f\\u00fcr bis zu Stunden \\u2713 30+ Haltestellen in Kopenhagen. Jetzt informieren und Tickets kaufen.\",\"inLanguage\":\"nl-NL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\\\/kopenhagen\\\/#breadcrumblist\"},\"datePublished\":\"2023-10-23T11:56:11+00:00\",\"dateModified\":\"2026-04-28T06:48:13+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\\\/\",\"name\":\"Hop-on\\\/Hop-off\",\"inLanguage\":\"nl-NL\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hop-on-hop-off.net\\\/nl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Kopenhagen: Hop-on\/Hop-off - Routes &amp; dienstregelingen 2026","description":"Hop-on\/Hop-off Kopenhagen: \u2713 Stadstour per bus \u2713 Tickets voor maximaal uren \u2713 30+ haltes in Kopenhagen. Vraag informatie aan en koop nu tickets.","canonical_url":"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.hop-on-hop-off.net\/nl#listItem","position":1,"name":"Startseite","item":"https:\/\/www.hop-on-hop-off.net\/nl","nextItem":{"@type":"ListItem","@id":"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/#listItem","name":"Kopenhagen: Hop-on\/Hop-off"}},{"@type":"ListItem","@id":"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/#listItem","position":2,"name":"Kopenhagen: Hop-on\/Hop-off","previousItem":{"@type":"ListItem","@id":"https:\/\/www.hop-on-hop-off.net\/nl#listItem","name":"Startseite"}}]},{"@type":"Organization","@id":"https:\/\/www.hop-on-hop-off.net\/nl\/#organization","name":"Hop-on\/Hop-off","url":"https:\/\/www.hop-on-hop-off.net\/nl\/","logo":{"@type":"ImageObject","url":"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png","@id":"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/#organizationLogo","width":365,"height":70,"caption":"Hop-on\/Hop-off Bus"},"image":{"@id":"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/#webpage","url":"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/","name":"Kopenhagen: Hop-on\/Hop-off - Routen & Fahrpl\u00e4ne 2026","description":"Hop-on\/Hop-off Kopenhagen: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu Stunden \u2713 30+ Haltestellen in Kopenhagen. Jetzt informieren und Tickets kaufen.","inLanguage":"nl-NL","isPartOf":{"@id":"https:\/\/www.hop-on-hop-off.net\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/#breadcrumblist"},"datePublished":"2023-10-23T11:56:11+00:00","dateModified":"2026-04-28T06:48:13+00:00"},{"@type":"WebSite","@id":"https:\/\/www.hop-on-hop-off.net\/nl\/#website","url":"https:\/\/www.hop-on-hop-off.net\/nl\/","name":"Hop-on\/Hop-off","inLanguage":"nl-NL","publisher":{"@id":"https:\/\/www.hop-on-hop-off.net\/nl\/#organization"}}]},"og:locale":"nl_NL","og:site_name":"Hop-on\/Hop-off.net -","og:type":"article","og:title":"Kopenhagen: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne 2026","og:description":"Hop-on\/Hop-off Kopenhagen: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu Stunden \u2713 30+ Haltestellen in Kopenhagen. Jetzt informieren und Tickets kaufen.","og:url":"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/","og:image":"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png","og:image:secure_url":"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png","article:published_time":"2023-10-23T11:56:11+00:00","article:modified_time":"2026-04-28T06:48:13+00:00","twitter:card":"summary_large_image","twitter:title":"Kopenhagen: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne 2026","twitter:description":"Hop-on\/Hop-off Kopenhagen: \u2713 Stadtrundfahrt im Bus \u2713 Tickets f\u00fcr bis zu Stunden \u2713 30+ Haltestellen in Kopenhagen. Jetzt informieren und Tickets kaufen.","twitter:image":"https:\/\/www.hop-on-hop-off.net\/wp-content\/uploads\/2023\/08\/hop-on-hop-off.png"},"aioseo_meta_data":{"post_id":"768","title":"Kopenhagen: Hop-on\/Hop-off - Routen &amp; Fahrpl\u00e4ne #current_year","description":"Hop-on\/Hop-off Kopenhagen: \u2713 Stadstour per bus \u2713 Tickets voor maximaal uren \u2713 30+ haltes in Kopenhagen. Vraag informatie aan en koop nu tickets.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-10-20 09:11:20","updated":"2026-04-28 07:04:10","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.hop-on-hop-off.net\/nl\" title=\"Startseite\">Startseite<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tKopenhagen: Hop-on\/Hop-off\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Startseite","link":"https:\/\/www.hop-on-hop-off.net\/nl"},{"label":"Kopenhagen: Hop-on\/Hop-off","link":"https:\/\/www.hop-on-hop-off.net\/nl\/kopenhagen\/"}],"featured_image_src":null,"_links":{"self":[{"href":"https:\/\/www.hop-on-hop-off.net\/nl\/wp-json\/wp\/v2\/pages\/768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hop-on-hop-off.net\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hop-on-hop-off.net\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hop-on-hop-off.net\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hop-on-hop-off.net\/nl\/wp-json\/wp\/v2\/comments?post=768"}],"version-history":[{"count":41,"href":"https:\/\/www.hop-on-hop-off.net\/nl\/wp-json\/wp\/v2\/pages\/768\/revisions"}],"predecessor-version":[{"id":2901,"href":"https:\/\/www.hop-on-hop-off.net\/nl\/wp-json\/wp\/v2\/pages\/768\/revisions\/2901"}],"wp:attachment":[{"href":"https:\/\/www.hop-on-hop-off.net\/nl\/wp-json\/wp\/v2\/media?parent=768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}